{"id":154705,"date":"2021-08-17T14:00:35","date_gmt":"2021-08-17T12:00:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/guardia-piemontese-grave-incidente-sulla-statale-283-coinvolte-due-auto-tre-feriti\/"},"modified":"2023-01-16T17:38:31","modified_gmt":"2023-01-16T16:38:31","slug":"419622-guardia-piemontese-grave-incidente-sulla-statale-283-coinvolte-due-auto-tre-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/419622-guardia-piemontese-grave-incidente-sulla-statale-283-coinvolte-due-auto-tre-feriti\/","title":{"rendered":"Guardia Piemontese, grave incidente sulla Statale 283. Tre feriti, interviene l&#8217;elisoccorso"},"content":{"rendered":"<p>GUARDIA PIEMONTESE (CS) &#8211; Un <strong>grave incidente stradale<\/strong> si \u00e8 verificato nel primo pomeriggio sulla S<strong>trada Statale &#8220;283 Delle Terme Luigiane&#8221;<\/strong> al chilometro 5,700 <strong>nel territorio di Guardia Piemontese<\/strong>. Per cause in corso di accertamento<b> due auto<\/b> (una Mercedes e una Fiat Punto che \u00e8 andata a schiantarsi contro un muro)<b> si sono scontrate<\/b> violentemente provocando <strong>il ferimento di tre persone, tra cui due ragazzi<\/strong>. Necessario anche<strong> l&#8217;intervento dell&#8217;elisoccorso<\/strong> fatto arrivare da Lamezia (Cosenza \u00e8 ancora senza supporto) e atterrato nei pressi di un viadotto, oltre che <strong>due ambulanze del 118<\/strong>.<\/p>\n\n<p><strong>La circolazione lungo la statale \u00e8 bloccata<\/strong> e la strada \u00e8 stata<strong> temporaneamente chiusa al transito<\/strong> con il traffico veicolare che \u00e8 stato provvisoriamente deviato sulla viabilit\u00e0 limitrofa con indicazioni in loco. Sul posto sono presenti, oltre ai sanitari del 118, i vigili del fuoco, l&#8217;Anas e le forze dell&#8217;ordine per la gestione della viabilit\u00e0 e per il ripristino della normale circolazione nel pi\u00f9 breve tempo possibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;incidente nel territorio di Guardia Piemontese  ha provocato 3 feriti. Statale chiusa al traffico per le operazioni di soccorso<\/p>\n","protected":false},"author":55,"featured_media":154706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-154705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=154705"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/154706"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=154705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=154705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=154705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}