{"id":154945,"date":"2021-08-22T16:24:08","date_gmt":"2021-08-22T14:24:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bisignano-perde-trattore-e-bestiame-in-un-incendio-e-lancia-una-raccolta-fondi\/"},"modified":"2023-01-16T17:38:47","modified_gmt":"2023-01-16T16:38:47","slug":"420147-bisignano-perde-trattore-e-bestiame-in-un-incendio-e-lancia-una-raccolta-fondi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/420147-bisignano-perde-trattore-e-bestiame-in-un-incendio-e-lancia-una-raccolta-fondi\/","title":{"rendered":"Bisignano, perde trattore e bestiame in un incendio e lancia una raccolta fondi"},"content":{"rendered":"<p dir=\"ltr\">BISIGNANO (CS) &#8211; &#8220;Mi chiamo Danilo e vivo a Bisignano, un piccolo paesino in provincia di Cosenza. Sono un agricoltore e vivo di questo&#8221;. <strong>Danilo Prezioso<\/strong> ha fatto partire una raccolta fondi su <a href=\"https:\/\/quicosenza.it\/news\/13618\" target=\"_blank\" rel=\"noopener noreferrer\">GoFundMe<\/a> che ha gi\u00e0 avuto 225 condivisioni.<\/p>\n<p dir=\"ltr\">&#8220;Purtroppo &#8211; scrive &#8211;<strong> a seguito di un incendio ho perso tutto il mio bestiame e i mezzi agricoli<\/strong> che mi servivano per lavorare e portare avanti la mia famiglia composta &#8211; prosegue &#8211; da mia moglie e i miei tre bambini&#8221;.<\/p>\n<p dir=\"ltr\">&#8220;In un attimo &#8211; continua &#8211; ho visto andare in fiamme il <strong>frutto di ogni mio sacrificio<\/strong>. I\u00a0 soldi &#8211; si legge &#8211; mi serviranno per iniziare a recuperare, nel pi\u00f9 breve tempo possibile, almeno il trattore per poter lavorare. &#8220;Non ho mai chiesto niente a nessuno &#8211; conclude Danilo &#8211; ma ora mi trovo davvero costretto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo l&#8217;appello di Danilo Prezioso, agricoltore che ha perso i mezzi necessari per svolgere la sua attivit\u00e0 a causa dei roghi di questi giorni<\/p>\n","protected":false},"author":21,"featured_media":154946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-154945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=154945"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/154946"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=154945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=154945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=154945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}