{"id":15521,"date":"2013-01-11T08:31:13","date_gmt":"2013-01-11T07:31:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15521"},"modified":"2023-01-17T13:13:40","modified_gmt":"2023-01-17T12:13:40","slug":"5174-prorogato-censimento-delle-delle-istituzioni-pubbliche","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5174-prorogato-censimento-delle-delle-istituzioni-pubbliche\/","title":{"rendered":"Prorogato Censimento delle istituzioni pubbliche"},"content":{"rendered":"<p><strong>REGGIO CALABRIA<\/strong> &#8211; Proroga fino al 31 Gennaio 2013 per la compilazione&nbsp;<span style=\"font-size: 12px;\">del questionario <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px;\">relativo al Censimento delle istituzioni pubbliche.<\/span><span style=\"font-size: 12px;\">&nbsp;Il tempo prolungato \u00e8 utile al completamento dell&#8217;operazione di&nbsp;<\/span><span style=\"font-size: 12px;\">raccolta dei dati.<\/span><\/p>\n<p>L\u2019Istat invita coloro che non l\u2019avessero ancora fatto a provvedere alla compilazione, esclusivamente via internet, entro e non oltre la nuova improrogabile scadenza.<\/p>\n<p><span style=\"font-size: 12px;\">Tutte le amministrazioni, gli enti e gli organismi pubblici hanno l\u2019obbligo di fornire i dati richiesti, in base all\u2019art. 7 del d.lgs. n. 322\/1989.&nbsp;<\/span><\/p>\n<p>I riferimenti per la richiesta di informazioni sono disponibili nell\u2019area Contatti del sito dedicato al censimento. On line anche i materiali del webinar \u201cRilevazione sulle istituzioni pubbliche, Istat risponde\u201c, dello scorso 7 dicembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Proroga fino al 31 Gennaio 2013 per la compilazione&nbsp;del questionario<\/p>\n","protected":false},"author":22,"featured_media":15522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-15521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15521"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/15522"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}