{"id":155961,"date":"2021-09-14T05:23:49","date_gmt":"2021-09-14T03:23:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/protesta-cliniche-misasi-e-san-bartolo-le-precisazioni-del-gruppo-morrone\/"},"modified":"2023-01-16T17:39:54","modified_gmt":"2023-01-16T16:39:54","slug":"422513-protesta-cliniche-misasi-e-san-bartolo-le-precisazioni-del-gruppo-morrone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/422513-protesta-cliniche-misasi-e-san-bartolo-le-precisazioni-del-gruppo-morrone\/","title":{"rendered":"Protesta cliniche Misasi e San Bartolo, le precisazioni del gruppo Morrone"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;In riferimento all\u2019articolo pubblicato ieri dal titolo <a href=\"https:\/\/quicosenza.it\/news\/13748\" target=\"_blank\" rel=\"noopener\">\u201cCosenza, dipendenti della Clinica Misasi e San Bartolo in presidio permanente&#8221;,<\/a> successivamente condiviso in rete, il <strong>gruppo Morrone fa presente quanto segue:<\/strong><\/p>\n<p>&#8220;A far data dal 24 aprile 2021, il Gruppo Morrone ha venduto il 100% delle partecipazioni societarie delle cliniche San Bartolo e Misasi al <strong>gruppo \u201cI Greco\u201d. <\/strong>La precisazione relativa al cambio di propriet\u00e0 risulta fondamentale al fine di non ricondurre la gestione delle suddette societ\u00e0, ed eventuali problematiche ad essa connesse, al gruppo Morrone e ad evitare che <strong>critiche spesso volgari e offensive vengano rivolte in maniera indiscriminata a chi non ha pi\u00f9 nulla a che fare con le cliniche San Bartolo e Misasi.<\/strong> Dopo la diffusione di questa precisazione, non saranno pi\u00f9 tollerate e saranno perseguite nelle sedi competenti, eventuali inopportuni e offensivi accostamenti&#8221;.<\/p>\n<p style=\"text-align: right;\"><strong>Il gruppo Morrone<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo le precisazioni del gruppo Morrone in merito alla protesta inscenata ieri mattina dai dipendenti delle cliniche Misasi e San Bartolo<\/p>\n","protected":false},"author":21,"featured_media":155962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-155961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/155961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=155961"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/155961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/155962"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=155961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=155961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=155961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}