{"id":15671,"date":"2013-01-14T12:46:26","date_gmt":"2013-01-14T11:46:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15671"},"modified":"2023-01-17T13:13:48","modified_gmt":"2023-01-17T12:13:48","slug":"5256-a-soverato-arriva-larte-di-enrique-vargas","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5256-a-soverato-arriva-larte-di-enrique-vargas\/","title":{"rendered":"A Soverato arriva l&#8217;arte di Enrique Vargas"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Re-Act, il teatro di residenza a Soverato, si prepara ad ospitare lo step finale <strong>del Teatro del Los Sentidos dell\u2019illustre Enrique Vargas,<\/strong> regista e ricercatore<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">teatrale di fama internazionale, la cui factory creativa composta da<strong> Giovanna Pezzullo, Nelson Jara e Patrizia Menichelli,<\/strong> ha elaborato un progetto composito e articolato su pi\u00f9 livelli. \u00abSi tratta di un tipologia teatrale completamente innovativa-ribadisce il condirettore artistico Emanuela Bianchi che ha seguito tutte le fasi del processo creativo- capace di recuperare nell\u2019atto teatrale tutta la dimensione dell\u2019esperienza, un atto di trasformazione, entrare in un modo per uscirne diversi, arricchiti. Quello che ci piace di questo teatro, \u00e8 questa capacit\u00e0 di risvegliare nelle persone che lo agiscono l\u2019atto del ricordo, come atto creativo. La poetica del l linguaggio dei sensi, sviluppata dal Teatro de los Sentidos, agisce nelle profondit\u00e0 della nostra vita. Un percorso ludico che vede interagire \u201d<strong>abitanti e immaginanti\u201d: attori e pubblico.<\/strong> L\u2019immaginante-spettatore \u00e8 attivo, sperimenta. L\u2019abitante-attore \u00e8 un propiziatore della memoria e la memoria si sa \u00e8 creativa. Ci\u00f2 che abbiamo vissuto e sperimentato si trasforma, si reinventa nel racconto, Quindi ri-crea. Questo percorso di laboratorio e l\u2019evento finale sono dedicati alla Poetica della Terra\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il 18 e 19 gennaio ci sar\u00e0 la dimostrazione finale del percorso di laboratorio aperta al pubblico in spazi sconosciuti del Teatro di Soverato. Essendo un lavoro in un luogo non convenzionale \u00e8 assolutamente obbligatoria la prenotazione segnalando la propria presenza. Comprendere una simile proposta nel cartellone di \u201cRe-act\u201d qualifica ulteriormente il progetto e il territorio al quale viene rivolto l\u2019invito dei suoi appassionati organizzatori. Per informazioni e prenotazioni chiamare il 329 4018888. In questi mesi di preparazione e didattica hanno partecipato 22 persone provenienti da diversi luoghi d\u2019Italia <strong>(dalla Liguria, Lazio e Sicilia oltre che ovviamente Calabria) all\u2019Australia.<\/strong> Per l\u2019evento conclusivo sono stati scelti 10 partecipanti: <strong>Emanuela Bianchi, Giovanni Carpanzano, Maria Grazia Bisurgi, Adolfo Oliviero, Maddalena Ascione, Stefania Mellace, Giovanni Muraca, Elisa Vignolo, Dario Rapicavoli, Elena Garufi.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>ENRIQUE VARGAS,<\/strong> regista e antropologo colombiano, si forma presso l&#8217;Accademia di Arte Drammatica di Bogot\u00e0 e presso l&#8217;Universit\u00e0 del Mitchigan, dove si laurea in Antropologia teatrale. Sono anni in cui compie anche le prime esperienze e collaborazioni lavorative, specialmente presso il prestigioso centro teatrale &#8220;Mama&#8221; di New York, dove in &#8220;Bread and Puppet&#8221; indaga con Peter Schuman la poetica dell&#8217;oggetto. In seguito &#8211; ottenuta la cattedra di Drammaturgia dell&#8217;immagine sensoriale presso l&#8217;universit\u00e0 nazionale di Bogot\u00e0 &#8211; dedica 15 anni allo studio dei giochi, rituali e miti dell&#8217;Amazzonia. E&#8217; del 1993 la fondazione della Compagnia Teatro de los Sentidos, all&#8217;interno della quale approfondisce il tema della poetica sensoriale, intesa come relazione espressiva tra corpo e memoria, tra plasticit\u00e0 dello spazio scenico ed esperienza sensorial teatrale. La sua ricerca ha dato vita alla trilogia &#8220;Sotto il segno del labirinto&#8221;. E&#8217; stato insignito di numerosi e prestigiosi riconoscimenti internazionali, tra i quali: Il primo premio del XXIV Salone nazionale degli artisti di Bogot\u00e0 ( Colombia) Premio miglior opera per pubblico e critica presso il Festival Internazionale di Teatro delle Nazioni, di Santiago del Cile. <strong>Premio Tuc\u00e0n d&#8217;Oro al VII Festival Latinoamericano del Teatro di C\u00e0diz.<\/strong> Riconoscimento <strong>Unesco al Festival Latinoamericano di Teatro di Bogot\u00e0.<\/strong> Premio nazionale di Drammaturgia di Bogot\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>PATRIZIA MENICHELLI,<\/strong> designer, performer, regista, ricercatrice e formatrice del Teatro de los Sentidos. Nel 1983 inizia la sua carriera teatrale come designer, dando avvio ad una intensa ricerca sulla costruzione del personaggio attraverso il costume e la maschera. Progressivamente la sua ricerca si \u00e8 spostata verso la rivisitazione dello \u201cspazio scenico\u201d, come idea di scena penetrabile, approfondendo la dimensione drammaturgica. Dal 1996 \u00e8 ricercatrice del Teatro de los Sentidos, indaga sul concetto di \u201cabitare\u201d uno spazio immaginario e collabora con il regista e drammaturgo Enrique Vargas alla conduzione di laboratori formativi sulla poetica dell\u2019Immagine Sensoriale in Italia e all\u2019estero. Segue la tournee internazionale del gruppo come performer e designer. Nelle ultime creazioni della compagnia \u00e8 assistente alla regia di Enrique Vargas. Si occupa inoltre di progetti interdisciplinari e in Italia collabora per la formazione degli adulti con istituzioni pubbliche e private: Museo Pecci (Dipartimento Educazione) Prato, Museo Ideale Leonardo Da Vinci a Vinci e a Firenze, Sovrintendenza Scolastica per la Toscana di Firenze, con il Teatro Metastasio di Prato, Seminarte e Centro Culturale il Funaro di Pistoia. \u00c8 direttore artistico dell\u2019Associazione Culturale Arcadia Ars In di Firenze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Re-Act, il teatro di residenza a Soverato, si prepara ad ospitare lo step finale del Teatro del Los Sentidos dell\u2019illustre Enrique Vargas, regista e ricercatore<\/p>\n","protected":false},"author":22,"featured_media":15672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34],"tags":[],"class_list":["post-15671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15671"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/15672"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}