{"id":157425,"date":"2021-10-16T13:00:28","date_gmt":"2021-10-16T11:00:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/oms-dipendenza-da-videogiochi-e-sindrome-della-capanna-tra-le-malattie\/"},"modified":"2023-01-16T17:41:33","modified_gmt":"2023-01-16T16:41:33","slug":"426731-oms-dipendenza-da-videogiochi-e-sindrome-della-capanna-tra-le-malattie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/426731-oms-dipendenza-da-videogiochi-e-sindrome-della-capanna-tra-le-malattie\/","title":{"rendered":"Oms, dipendenza da videogiochi e sindrome della capanna tra le malattie"},"content":{"rendered":"<p>ROMA &#8211; L&#8217;Organizzazione mondiale della sanit\u00e0 (OMS) ha incluso il &#8220;<strong>gaming disorder<\/strong>&#8220;, ossia il disturbo da gioco, nella sua lista delle malattie (International Statistical Classification of Diseases and Related Health Problems). Il disturbo comprende una serie di atteggiamenti <strong>legati al mancato controllo sul gioco <\/strong>e grande priorit\u00e0 data ad esso tanto da renderlo pi\u00f9 importante di qualsiasi altra attivit\u00e0 quotidiana e di ogni interesse esistenziale. La posizione assunta dall\u2019Oms rispetto alla <strong>dipendenza da videogames<\/strong> deriva dalle molteplici segnalazioni arrivate dagli esperti, gi\u00e0 operativi con cliniche per la disintossicazione.<\/p>\n<p>Il pericolo di una <strong>dipendenza patologica<\/strong> incombe soprattutto sui pi\u00f9 giovani che nei videogiochi trovano una dimensione particolare nella quale confrontarsi con se stessi e con i compagni di gioco on line e ad essa dedicano tempo ed energie. <strong>Una grande spinta al gaming disorder \u00e8 stata data, inevitabilmente, anche dal periodo di lockdown<\/strong> vissuto agli inizi della pandemia da covid-19 che rappresenta il contraccolpo psicologico delle esperienze dei mesi scorsi. Costretti in casa, bambini e adolescenti hanno trascorso gran parte del proprio tempo attaccati ad un joistick on line, ma anche off line, alle prese con competizioni virtuali. Tempi lunghissimi durante i quali il distacco dalla quotidianit\u00e0 diventava progressivo e sempre pi\u00f9 marcato, sino ad arrivare ad una sorta di isolamento sociale peggiorato da sbalzi d\u2019umore ed esclusione di tutto ci\u00f2 che non abbia attinenza con i risultati del gioco. Una condizione preoccupante che diventa l\u2019unico interesse e l\u2019unica valvola di sfogo e si accompagna a <strong>disturbi alimentari e del sonno, depressione, ansia, stress, mal di testa e persino crisi epilettiche.<\/strong><\/p>\n<h3>Sindrome della capanna<\/h3>\n<p>Rimanere chiusi in casa, in camera a giocare pu\u00f2 far sviluppare anche la cosiddetta <strong>sindrome della capanna o del prigioniero<\/strong>, ossia la paura di uscire e lasciare la propria casa, il luogo che per mesi ci ha fatto sentire al sicuro, al riparo da qualsiasi pericoloso agente esterno, entro le confortevoli mura della propria stanza in compagnia della fidata consolle e dello smartphone, ignorando qualsiasi richiamo esterno. Per diverse ragioni, ma anche a causa di meccanismi del tutto inconsci, ansia, paura e frustrazione hanno preso il sopravvento nello stato d\u2019animo di queste persone che, oltre tutto, hanno manifestato contestualmente anche disturbi del sonno, depressione e spiccata tendenza all\u2019irascibilit\u00e0. Effetti per certi versi riconducibili a quelli percepiti da chi \u00e8 stato costretto ad una lunga degenza o da chi, vivendo in zone del mondo dove il freddo invernale impedisce di uscire, \u00e8 costretto a restare chiuso in casa per mesi e mesi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-426733 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/10\/sindrome-della-capanna.jpg\" alt=\"\" width=\"499\" height=\"426\" title=\"\"><\/p>\n<p><strong>\u00c8 bene non sottostimare la gravit\u00e0 di questa sindrome<\/strong>: pi\u00f9 tende a cronicizzarsi e maggiore \u00e8 la probabilit\u00e0 che lasci il segno. Sono molteplici le cause responsabili di un comportamento protettivo come questo, tra cui il terrore verso il mondo esterno, la paura di ammalarsi, il timore di contagiare i propri cari e la convinzione di non ritrovare pi\u00f9 il mondo che si conosceva prima. L\u2019aiuto di un neuropsichiatra infantile \u00e8 importante per recuperare terreno in una situazione simile, cos\u00ec come il recupero delle abitudini pi\u00f9 salutari necessarie a ristabilire priorit\u00e0 e rituali sani. Comunicare e rassicurare soprattutto i bambini \u00e8 il primo passo in un percorso da puntellare con impegni quotidiani grazie a quali scandire il tempo a disposizione, evitando che tutto si riduca ad una partita interminabile ai videogames. Riprendere le corrette abitudini non \u00e8 facile e come qualsiasi altra dipendenza, anche il gaming disorder conosce momenti di particolare criticit\u00e0, ma con attenzione e rassicurazioni pu\u00f2 essere sconfitto. Di aiuto \u00e8 sicuramente la prevenzione negli atteggiamenti sbagliati: le regole e l\u2019organizzazione del tempo sono fondamentali nella vita di bambini e adolescenti ed il loro rispetto scongiura il rischio di assuefazione ad abitudini pericolose.<\/p>\n<p>E&#8217; la prima volta, evidenzia Giovanni D&#8217;Agata, presidente dello \u201cSportello dei Diritti\u201d, che l&#8217;Oms include una dipendenza &#8220;tecnologica&#8221; nella lista delle malattie. Fra i sintomi a cui i medici dovrebbero prestare attenzione ci sono il fatto che il paziente dia priorit\u00e0 ai videogame &#8220;<strong>fino al punto in cui il gioco prevale sugli altri interessi della vita&#8221;<\/strong>, l&#8217;inabilit\u00e0 di controllare quanto spesso o quanto a lungo si gioca, l&#8217;ignorare le conseguenze negative del giocare troppo. In conclusione ricordiamo quanto riportato da uno studio della Boston University School of Public Health (pubblicato da JAMA) che ha evidenziato un aumento significativo del numero di adulti americani con sintomi depressivi dal momento in cui \u00e8 iniziata l\u2019emergenza sanitaria negli Stati Uniti (dall\u20198,5% iniziale al 27,8% di met\u00e0 aprile). <strong>Dopo eventi traumatici del genere (Ebola, 11 settembre e altro) la depressione nella popolazione al massimo raddoppiava, nel caso del Covid-19 \u00e8 persino triplicata<\/strong>.Quindi il messaggio che vogliamo dare \u00e8 s\u00ec di stare attenti all\u2019ansia e alla preoccupazione rientrando nella propria normalit\u00e0, ma di non esitare a rivolgersi a specialisti se i sintomi dovessero perdurare, perch\u00e9 si potrebbe essere in una situazione simile ai sintomi prodotti da stress post-traumatico o, comunque, essere di fronte alla slatentizzazione di qualcosa gi\u00e0 preesistente ma latente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ossessione per i videogiochi diventa malattia mentale. Bambini e adolescenti sono spesso vittime di gaming disorder: cosa fare?<\/p>\n","protected":false},"author":42,"featured_media":157426,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-157425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/157425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=157425"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/157425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/157426"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=157425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=157425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=157425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}