{"id":157506,"date":"2021-10-14T13:38:57","date_gmt":"2021-10-14T11:38:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/in-calabria-stabile-la-curva-dei-contagi-115-positivi-e-2-decessi\/"},"modified":"2023-01-16T17:41:39","modified_gmt":"2023-01-16T16:41:39","slug":"426915-in-calabria-stabile-la-curva-dei-contagi-115-positivi-e-2-decessi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/426915-in-calabria-stabile-la-curva-dei-contagi-115-positivi-e-2-decessi\/","title":{"rendered":"In Calabria stabile la curva dei contagi: +115 positivi e 2 decessi"},"content":{"rendered":"<p><span class=\"primamaiuscola\">CATANZARO &#8211; Nel bollettino odierno diramato dal dipartimento salute rimangono <strong>stabili i contagi: sono +115<\/strong> a fronte di <strong>+3.187 tamponi processati<\/strong>, sia antigenici che molecolari. Sono <strong>due le vittime accertate<\/strong> di cui una a Cosenza e l&#8217;altra a Reggio Calabria. <strong>Stabili gli ingressi nei reparti ordinari e in terapia intensiva<\/strong> che non segnano n\u00e9 un aumento n\u00e9 un calo. Il tasso di positivit\u00e0 scende attestandosi al 3,61%. Il numero delle persone guarite segna +113.<\/span><\/p>\n<p>La provincia che oggi conta pi\u00f9 pi\u00f9 positivi \u00e8 Vibo Valentia +37 seguita da Cosenza +35. Segue la provincia di Reggio Calabria con un calo +19 e Crotone +14. Si mantengono ancora bassi i nuovi casi a Catanzaro +7. Sono 3 i nuovi positivi accertati sotto la categoria Altra Regione o Stato Estero.<\/p>\n<p><span class=\"primamaiuscola\">I<\/span>n Calabria, ad oggi, il totale dei tamponi eseguiti sono stati 1.233.584. Le persone risultate positive al Coronavirus sono 85.358 rispetto a ieri. Questi sono i dati giornalieri relativi all\u2019epidemia da Covid-19 comunicati dai Dipartimenti di Prevenzione delle AA.SS.PP. della Regione Calabria.<\/p>\n<h4><span style=\"color: #3366ff;\">Territorialmente, dall\u2019inizio dell\u2019epidemia, i casi positivi sono cos\u00ec distribuiti:<\/span><\/h4>\n<p><strong>Catanzaro<\/strong>: CASI ATTIVI 87 (6 in reparto, 1 in terapia intensiva, 80 in isolamento domiciliare); CASI CHIUSI 11.388 (11.232 guariti, 156 deceduti);<\/p>\n<p><strong>Cosenza<\/strong>: CASI ATTIVI 1.263 (18 in reparto, 4 in terapia intensiva, 1.241 in isolamento domiciliare); CASI CHIUSI 26.463 (25.814 guariti, 649 deceduti);<\/p>\n<p><strong>Crotone<\/strong>: CASI ATTIVI 236 (5 in reparto, 0 in terapia intensiva, 231 in isolamento domiciliare) CASI CHIUSI 8.104 (7.989 guariti, 115 deceduti);<\/p>\n<p><strong>Reggio Calabria<\/strong>: CASI ATTIVI 797 (54 in reparto, 6 in terapia intensiva, 737 in isolamento domiciliare); CASI CHIUSI 29.114 (28.714 guariti, 400 deceduti);<\/p>\n<p><strong>Vibo Valentia<\/strong>: CASI ATTIVI 251 (7 in reparto, 0 in terapia intensiva, 244 in isolamento domiciliare); CASI CHIUSI 6,317 (6,217 guariti, 100 deceduti)<\/p>\n<p><strong>L&#8217;asp di Crotone comunica 17 nuovi soggetti positivi di cui 3 fuori regione<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La provincia che oggi conta pi\u00f9 pi\u00f9 positivi \u00e8 Vibo Valentia +37 seguita da Cosenza +35. Stabili i ricoveri nei reparti ordinari e in terapia intensiva<\/p>\n","protected":false},"author":58,"featured_media":157507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,1],"tags":[19],"class_list":["post-157506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/157506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=157506"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/157506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/157507"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=157506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=157506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=157506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}