{"id":15799,"date":"2013-01-15T16:56:36","date_gmt":"2013-01-15T15:56:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15799"},"modified":"2023-01-17T13:13:55","modified_gmt":"2023-01-17T12:13:55","slug":"5323-cinema-annus-horribilis-per-film-italiani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5323-cinema-annus-horribilis-per-film-italiani\/","title":{"rendered":"Cinema: &#8220;annus horribilis&#8221; per film italiani"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROMA<\/strong> &#8211; &#8216;Annus horribilis&#8217; per il cinema in Italia e per la cinematografia di casa nostra. Il 2012 si chiude con dati negativi per l&#8217;industria della<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">celluloide: diminuiscono del 10% gli spettatori e dell&#8217;8% gli incassi.<br \/>&nbsp; Diminuisce anche la quota di mercato dei film italiani che, insieme alle coproduzioni, ha registrato nel 2012 il 26,5% delle presenze a fronte del 37,6% nel 2011. Diminuiscono le presenze anche per i film americani che passano dai 47,4 milioni di spettatori nel 2011 ai 46,7 del 2012. Sono questi alcuni dei dati del mercato cinematografico 2012, rilevati da Cinetel, presentati oggi a Roma dalle associazioni degli esercenti Anec e Anem, e dai distributori e produttori dell&#8217;Anica. Il calo complessivo degli spettatori fa comunque aumentare in quota la percentuale dei film Usa che si attesta al 51,2% nel 2012 contro il 46,8% del 2011. Aumento sia in valore assoluto che in quota per i film europei, passati dal 13,8% al 18,3% delle presenze. Rimasto praticamente invariato il numero di film distribuiti: 363 nel 2012, 360 nel 2011. Per valutare il calo dei dati del cinema non si puo&#8217; prescindere dal considerare il contesto piu&#8217; ampio della grave crisi economica generale. Questo contesto ha portato una minore propensione alla spesa da parte degli spettatori, malgrado i dati rilevino che il prezzo medio del biglietto e&#8217; aumentato nel 2012 solo dello 0,7% rispetto al 2011 e che, piu&#8217; in generale, gli aumenti negli ultimi dieci anni sono stati nettamente inferiori al tasso di inflazione. Non mancano, in questo scenario, segnali positivi. Da rilevare in particolare che, superato il periodo estivo che ha visto un calo delle presenze del 33%, nella seconda parte dell&#8217;anno, dal primo agosto a fine dicembre la situazione e&#8217; cambiata in positivo con un incremento dei biglietti staccati del 3,2% rispetto all&#8217;analogo periodo del 2011. Inoltre ha avuto successo la decisione di tutta l&#8217;industria di anticipare l&#8217;uscita dei film dal venerdi&#8217; al giovedi&#8217;, iniziativa che ha portato da ottobre ad un aumento delle presenze del 15,8% nella nuova giornata di esordio. Di fronte alla situazione descritta dai dati le associazioni, in un quadro di sempre maggiore collaborazione, stanno avviando iniziative comuni che possano apportare cambiamenti significativi e strutturali al mercato. In primo luogo e&#8217; necessario incentivare e stabilizzare il consumo di cinema nei mesi estivi. Le categorie stanno lavorando per trovare accordi che rendano piu&#8217; appetibile per il pubblico andare al cinema in quel periodo. Oltre a una piu&#8217; consistente offerta di film, sia internazionali che italiani, ANEC, ANICA e ANEM hanno deciso di organizzare nella prima meta&#8217; di maggio un evento promozionale, la Festa del Cinema, durante la quale per una settimane il biglietto costera&#8217; 3 euro. Tra le altre iniziative l&#8217;adesione alla Carta dello Studente &#8220;Io Studio&#8221;, promossa dal MiUR, che da&#8217; la possibilita&#8217; a circa 2,5 milioni di studenti delle scuole superiori di usufruire di una riduzione del 40% sul prezzo del biglietto dei cinema nei primi tre giorni della settimana.<\/p>\n<p style=\"text-align: justify;\">(Fonte AGI) .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; &#8216;Annus horribilis&#8217; per il cinema in Italia e per la cinematografia di casa nostra. Il 2012 si chiude con dati negativi per l&#8217;industria della<\/p>\n","protected":false},"author":22,"featured_media":15800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-15799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15799"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/15800"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}