{"id":158807,"date":"2021-11-11T19:07:52","date_gmt":"2021-11-11T18:07:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-tua-fine-e-vicinissima-minacce-a-gasparri-solidarieta-di-occhiuto\/"},"modified":"2023-01-16T17:43:09","modified_gmt":"2023-01-16T16:43:09","slug":"430380-la-tua-fine-e-vicinissima-minacce-a-gasparri-solidarieta-di-occhiuto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/430380-la-tua-fine-e-vicinissima-minacce-a-gasparri-solidarieta-di-occhiuto\/","title":{"rendered":"&#8220;La tua fine \u00e8 vicinissima&#8221;, minacce a Gasparri. Solidariet\u00e0 di Occhiuto"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;&#8216;<strong>La tua fine \u00e8 vicinissima&#8217;, &#8216;una brutta fine tra mille dolori&#8217;, &#8216;qualcuno ti spari addosso<\/strong>&#8216;&#8221;. Sono alcune delle minacce rivolte contro\u00a0 <strong>Maurizio Gasparri<\/strong> e diffuse dall&#8217;ufficio stampa del Senato di Forza Italia. Si tratta di una lettera anonima &#8220;proveniente da Padova&#8221;, che &#8220;contiene numerose minacce di morte al senatore Gasparri e per questo \u00e8 stata inoltrata con una denuncia alle forze dell&#8217;ordine&#8221;.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fgasparri.it%2Fposts%2F10158838093748600&amp;show_text=true&amp;width=500\" width=\"500\" height=\"666\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h4>Solidariet\u00e0 di Occhiuto e Salvini<\/h4>\n<div>&#8220;Desidero esprimere la mia vicinanza al senatore Maurizio Gasparri, per le assurde e deliranti minacce ricevute tramite una lettera anonima. Queste intimidazioni non lo faranno certo arretrare, ed anzi siamo sicuri che gli daranno ancora pi\u00f9 convinzione nella sua azione politica&#8221;. Lo scrive su Twitter <strong>Roberto Occhiuto<\/strong>, presidente della Regione Calabria.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-430387 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/11\/Twitter-Roberto-Occhiuto.png\" alt=\"\" width=\"502\" height=\"214\" title=\"\"><\/div>\n<p>Tutta la mia solidariet\u00e0 a Maurizio Gasparri&#8221;. Lo ha detto<strong> Matteo Salvini<\/strong> parlando con i giornalisti a Reggio Calabria, dove \u00e8 giunto nel pomeriggio per partecipare ad una riunione di partito, in riferimento alla lettera anonima con minacce di morte recapitata al senatore di Forza Italia. &#8220;La mia solidariet\u00e0 &#8211; ha aggiunto Salvini &#8211; non pu\u00f2 mancare, cos\u00ec come l&#8217;ho espressa di recente al sindaco di Milano Giuseppe Sala o a chiunque altro venga attaccato, insultato, minacciato, diffamato&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una lettera anonima che &#8220;contiene numerose minacce di morte al senatore di Forza Italia&#8221; e diffusa dall&#8217;ufficio stampa del partito<\/p>\n","protected":false},"author":58,"featured_media":158808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-158807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/158807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=158807"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/158807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/158808"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=158807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=158807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=158807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}