{"id":159639,"date":"2021-11-29T11:52:44","date_gmt":"2021-11-29T10:52:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/vaccini-loizzo-ad-acri-smantellato-il-centro-vaccinale-per-un-evento\/"},"modified":"2023-01-16T17:44:05","modified_gmt":"2023-01-16T16:44:05","slug":"432415-vaccini-loizzo-ad-acri-smantellato-il-centro-vaccinale-per-un-evento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/432415-vaccini-loizzo-ad-acri-smantellato-il-centro-vaccinale-per-un-evento\/","title":{"rendered":"Vaccini, Loizzo: &#8220;ad Acri smantellato il centro vaccinale per un evento&#8221;"},"content":{"rendered":"<p>ACRI (CS) &#8211; &#8220;Il Comune di Acri ha smantellato il centro vaccinale di <strong>Cappella Sanseverino<\/strong> per consentire l&#8217;edizione di Assaporagionando. Una decisione assai discutibile che poteva essere evitata&#8221;. A dirlo \u00e8 Simona Loizzo, capogruppo della Lega in consiglio regionale che sottolinea: &#8220;L&#8217;amministrazione comunale poteva scegliere un <strong>posto diverso per la manifestazione<\/strong>, certamente <strong>meritoria e degna di attenzione<\/strong>, senza mettere a <strong>repentaglio un hub vaccinale<\/strong> strategico per la popolazione&#8221;.<\/p>\n<p>&#8220;Una decisione &#8211; prosegue l&#8217;esponente leghista in consiglio regionale &#8211; che arriva proprio nel momento in cui il governo istituisce il super green pass in considerazione della quarta ondata della pandemia. L&#8217;auspicio ora \u00e8 che si trovi una soluzione per il centro vaccinale &#8211; conclude Loizzo &#8211; <strong>nell&#8217;interesse della salute dei cittadini acresi<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Simona Loizzo, capogruppo della Lega in consiglio regionale sottolinea: &#8220;si trovi una soluzione nell&#8217;interesse dei cittadini acresi&#8221;<\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-159639","post","type-post","status-publish","format-standard","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/159639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=159639"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/159639\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=159639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=159639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=159639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}