{"id":159998,"date":"2021-12-05T08:56:28","date_gmt":"2021-12-05T07:56:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/liss-al-momento-confermati-nove-casi-omicron-in-italia\/"},"modified":"2023-01-16T17:44:29","modified_gmt":"2023-01-16T16:44:29","slug":"433357-liss-al-momento-confermati-nove-casi-omicron-in-italia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/433357-liss-al-momento-confermati-nove-casi-omicron-in-italia\/","title":{"rendered":"L&#8217;Iss: &#8220;al momento confermati nove casi Omicron in Italia&#8221;"},"content":{"rendered":"<p>ROMA &#8211; L&#8217;Istituto superiore di sanit\u00e0 conferma al momento <strong>nove casi della variante Omicron in Italia<\/strong>. &#8220;Nella piattaforma ICoGen ci sono al momento 9 sequenze depositate per la variante Omicron: <strong>7 del cluster relativo al paziente indice;<\/strong> <strong>1 trovata in un paziente in provincia di Bolzano;<\/strong> <strong>1 in un paziente in Veneto<\/strong>&#8220;, scrive l&#8217;Istituto superiore di Sanit\u00e0 su Twitter. Per la prima volta una persona in Alto Adige \u00e8 risultata positiva alla variante del coronavirus &#8220;Omicron&#8221;.<\/p>\n<p>Si tratta di una donna del burgraviato rientrata in Alto Adige dal Sudafrica a fine novembre. Come previsto si era sottoposta a tampone molecolare sia prima della partenza, a Citt\u00e0 del Capo, che all&#8217;arrivo a Monaco, entrambe le volte con risultato negativo. In seguito le autorit\u00e0 competenti hanno informato l&#8217;Azienda Sanitaria dell&#8217;Alto Adige di un caso positivo al SARS-CoV-2 riscontrato sullo stesso volo. La donna \u00e8 stata immediatamente sottoposta a un ulteriore tampone PCR che ha dato esito positivo, informa l&#8217;Azienda sanitaria. Ieri sera i risultati del sequenziamento, eseguito presso il Laboratorio Aziendale di Microbiologia e Virologia, hanno <strong>confermato che si tratta della variante Omicron.<\/strong><\/p>\n<p>La paziente si trova in isolamento ed ha riferito sintomi lievi. L&#8217;unico contatto stretto, peraltro asintomatico, \u00e8 in quarantena. Il tampone Pcr \u00e8 in corso. La sorveglianza della circolazione di nuove varianti attualmente prevede che si effettui il sequenziamento di tutti i tamponi Pcr positivi di viaggiatori di ritorno da aree a rischio, come anche quando vi sono segnalazioni con motivi di sospetto. La variante Omicron, informa l&#8217;Azienda sanitaria, ha evidenziato <strong>una maggiore velocit\u00e0 di trasmissione.<\/strong> In molti casi il decorso nei pazienti vaccinati o guariti da Covid-19 risulta lieve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La variante Omicron ha evidenziato una maggiore velocit\u00e0 di trasmissione. In molti casi il decorso nei pazienti vaccinati o guariti da Covid-19 risulta lieve&#8221;<\/p>\n","protected":false},"author":61,"featured_media":159999,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-159998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/159998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=159998"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/159998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/159999"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=159998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=159998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=159998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}