{"id":160347,"date":"2021-12-11T11:17:48","date_gmt":"2021-12-11T10:17:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rientra-dalla-svizzera-per-natale-arrestato-ricercato-calabrese\/"},"modified":"2023-01-16T17:44:53","modified_gmt":"2023-01-16T16:44:53","slug":"434163-rientra-dalla-svizzera-per-natale-arrestato-ricercato-calabrese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/434163-rientra-dalla-svizzera-per-natale-arrestato-ricercato-calabrese\/","title":{"rendered":"Rientra dalla Svizzera per Natale, arrestato un ricercato calabrese"},"content":{"rendered":"<p>TREVISO &#8211; E&#8217; stato arrestato in provincia di Novara dai Carabinieri del Nucleo Investigativo di Treviso<strong> Salvatore Bitonti, 45 anni, di origini calabresi<\/strong>, su ordine di carcerazione emesso dalla Procura Generale di Trieste a febbraio. Bitonti deve espiare una condanna definitiva a 5 anni e 4 mesi di reclusione per estorsione, rapina e incendio aggravati dal <strong>metodo mafioso<\/strong>, commessi in provincia di Pordenone nel 2012 e 2013.<\/p>\n<h4>Bitonti chiedeva il pizzo agli imprenditori pordenonesi<\/h4>\n<p>La vicenda riguardava alcuni imprenditori pordenonesi che erano stati a lungo minacciati, intimiditi e ai quali erano state estorte ingenti somme di denaro; per questo la Procura aveva configurato l&#8217;aggravante del &#8220;metodo mafioso&#8221;. <strong>Gli investigatori dell&#8217;Arma erano da tempo sulle sue tracce<\/strong>, con ricerche estese anche in ambito internazionale, in collaborazione il Servizio di Cooperazione Internazionale di Polizia di Roma, della polizia del Canton Ticino e l&#8217;Arma di Novara.<\/p>\n<p>Grazie alla collaborazione della polizia cantonale svizzera Bitonti \u00e8 stato dapprima localizzato Oltralpe ed infine rintracciato alcune ore fa nel Novarese, <strong>presso l&#8217;abitazione di un congiunto<\/strong>, dove probabilmente aveva fatto rientro dall&#8217;estero in vista delle Festivit\u00e0 natalizie. Al termine delle formalit\u00e0 di rito \u00e8 stato condotto in carcere a Novara, a disposizione dell&#8217;Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli investigatori dell&#8217;Arma di Treviso erano da tempo sulle sue tracce. L&#8217;uomo \u00e8 accusato di estorsione con l&#8217;aggravante del metodo mafioso<\/p>\n","protected":false},"author":58,"featured_media":160348,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,1],"tags":[19],"class_list":["post-160347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160347"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160348"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}