{"id":160351,"date":"2021-12-11T11:50:10","date_gmt":"2021-12-11T10:50:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tensione-tra-occhiuto-e-i-sindacati-rispetti-di-piu-le-nostre-scelte\/"},"modified":"2023-01-16T17:44:53","modified_gmt":"2023-01-16T16:44:53","slug":"434174-tensione-tra-occhiuto-e-i-sindacati-rispetti-di-piu-le-nostre-scelte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/434174-tensione-tra-occhiuto-e-i-sindacati-rispetti-di-piu-le-nostre-scelte\/","title":{"rendered":"Tensione tra Occhiuto e i sindacati &#8220;rispetti di pi\u00f9 le nostre scelte&#8221;"},"content":{"rendered":"<p><strong>CATANZARO &#8211; Emergono i primi attriti tra i sindacati e il neo governo calabrese dopo che Cgil<\/strong>\u00a0ed\u00a0<strong>Uil<\/strong>\u00a0hanno annunciato lo sciopero generale il prossimo 16 dicembre contro la manovra varata dal Governo Draghi.\u00a0<strong>Roberto Occhiuto<\/strong>, presidente della\u00a0<strong>Regione Calabria<\/strong>, intervenendo qualche giorno fa a \u201cTg2Post\u201d, su Rai2, ha detto: \u201ci sindacati avevano dimostrato grande disponibilit\u00e0 e responsabilit\u00e0 in questo anno e mezzo di pandemia. Ricordo, ad esempio, durante il primo lockdown un accordo importante con le organizzazioni datoriali&#8221;.<\/p>\n<p>Il governatore della Calabria incalza specificando che &#8220;evidentemente<strong> Cgil e Uil hanno dimenticato quello che il Paese ha subito<\/strong> in questo anno e mezzo. E lo hanno dimenticato oggi, che grazie al governo Draghi abbiamo un Pil che cresce del 6%. La legge di bilancio \u00e8 una manovra espansiva. Questo \u00e8 un passo indietro del sindacato. Io credo per\u00f2 che il governo andr\u00e0 avanti, e la maggior parte delle forze politiche che sostengono l\u2019esecutivo ha preso giustamente le distanze dal sindacato\u201d, conclude Occhiuto&#8221;.<\/p>\n<h4>Bombardieri, Occhiuto rispetti di pi\u00f9 scelte sindacati<\/h4>\n<p>Il nuovo presidente della Regione Calabria, Roberto Occhiuto, &#8220;dovrebbe avere pi\u00f9 rispetto delle scelte confederali. Non credo che sia lui a dover dare giudizi sulle scelte che fanno le organizzazioni sindacali&#8221;. Lo ha dichiarato il segretario generale della Uil Pierpaolo Bombardieri, rispondendo a una domanda sulle prime mosse del nuovo governo regionale calabrese. Il governatore, a parere di Bombardieri, calabrese di Marina di Gioiosa Ionica, &#8220;magari si dovrebbe preoccupare un po&#8217; di pi\u00f9 di far ripartire questa regione&#8221;. Occhiuto, esponente di FI, aveva criticato la decisione di proclamare lo sciopero generale.<br \/>\nADV<\/p>\n<h4>&#8220;Governo dia risposte sui licenziamenti&#8221;<\/h4>\n<p>&#8220;E&#8217; uno dei temi che abbiamo posto con molta determinazione al Governo: assistiamo a licenziamenti fatti con sms, sulla piattaforma Zoom. Abbiamo chiesto al Governo una discussione pi\u00f9 approfondita sul tema delle delocalizzazioni, ma il decreto non viene fuori&#8221;, ha detto Pierpaolo Bombardieri, segretario generale della Uil. &#8220;Sono questi &#8211; ha aggiunto &#8211; i punti sui quali <strong>chiediamo al Governo di dare risposte<\/strong>, non solo a noi e non tanto a noi, ma alle tante persone che rischiano di essere senza lavoro da domani&#8221;.<\/p>\n<h4>Manovra: Bombardieri, &#8220;Rispetto la Cisl, pretendo altrettanto&#8221;<\/h4>\n<p>&#8220;Io ho molto rispetto per le decisioni delle altre organizzazioni sindacali confederali. In questo paese non c&#8217;\u00e8 un sindacato unico, ci sono tre grandi centrali sindacali che hanno storie diverse, tradizioni diverse. Ho sempre molto rispetto delle scelte degli altri e ne pretendo altrettanto&#8221;. E&#8217; la risposta data dal segretario generale della Uil, Pierpaolo Bombardieri, a chi gli ha chiesto un commento sulla mancata adesione della Cisl allo sciopero indetto con la Cgil contro la manovra economica.<\/p>\n<h4>&#8220;Serve riforma che combatta 110 mld evasione&#8221;<\/h4>\n<p>&#8220;Serve una riforma fiscale che sia in grado di combattere 110 miliardi di evasione di cui non si parla pi\u00f9; di effettuare una redistribuzione <strong>partendo dalle categorie che oggi stanno in grande difficolt\u00e0<\/strong>; occorre un&#8217;attenzione sul tema del Welfare, ai giovani, alle donne, a chi ha lavorato per 41 anni di fila e vuole andare in pensione&#8221;. Lo ha detto il segretario generale della Uil, Pierpaolo Bombardieri, rispondendo a una domanda sui temi della mobilitazione generale indetta dal suo sindacato insieme con la Cgil contro la manovra economica. &#8220;Questi sono i temi principali &#8211; ha spiegato Bombardieri, che si trova in Calabria per una iniziativa unitaria con la Cgil &#8211; ma c&#8217;\u00e8 una piattaforma unitaria sulla quale tutti ci siamo impegnati&#8221;.<\/p>\n<h4>&#8220;Bisogna costruire un Paese diverso&#8221;<\/h4>\n<p>&#8220;Chiediamo un Paese diverso. Chiediamo un Paese che sia in grado di interrogarsi sul fatto che <strong>ci sono tanti disagi e tante disuguaglianze<\/strong>, c&#8217;\u00e8 una narrativa che tende a dire che va tutto bene&#8221;. Lo ha detto Pierpaolo Bombardieri, segretario geneale della Uil, incontrando i giornalisti a Lamezia Terme (Cz) dove partecipa a una manifestazione organizzata da Cgil e Uil Calabria sulla manovra economica del Governo contro la quale le due centrali sindacali hanno proclamato lo sciopero generale.<br \/>\n&#8220;Siamo <strong>in Calabria<\/strong>, siamo nel Mezzogiorno &#8211; ha aggiunto &#8211; basta parlare con i tanti giovani,<strong> i tanti disoccupati, i tanti anziani che non hanno servizi<\/strong>. Vorremmo partire da qua per spiegare al Governo e alla politica che c&#8217;\u00e8 l&#8217;esigenza di costruire un Paese diverso&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emergono i primi attriti dopo che Cgil\u00a0ed\u00a0Uil\u00a0hanno annunciato lo sciopero generale il prossimo 16 dicembre contro la manovra economica<\/p>\n","protected":false},"author":58,"featured_media":160352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[19],"class_list":["post-160351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160351"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160352"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}