{"id":160611,"date":"2021-12-18T06:00:29","date_gmt":"2021-12-18T05:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mormanno-un-milione-e-700mila-euro-per-riqualificare-il-borgo\/"},"modified":"2023-01-16T17:45:12","modified_gmt":"2023-01-16T16:45:12","slug":"434796-mormanno-un-milione-e-700mila-euro-per-riqualificare-il-borgo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/434796-mormanno-un-milione-e-700mila-euro-per-riqualificare-il-borgo\/","title":{"rendered":"Mormanno, un milione e 700mila euro per riqualificare il borgo"},"content":{"rendered":"<p>MORMANNO (CS) &#8211; Una citt\u00e0 dinamica, che guarda alle sfide del prossimo futuro in maniera integrata con il territorio. Mormanno ha candidato all&#8217;attenzione di alcuni bandi ministeriali e regionali ben tre progetti di ampio respiro per un <strong>valore complessivo di un milione e settecentomila euro. <\/strong><\/p>\n<p>Il primo riguarda il recupero e la riqualificazione del <strong>Parco delle Rimembranze<\/strong> per un importo complessivo di 15.000,00\u20ac. La somma invece di 130 mila euro \u00e8 stata richiesta per <strong>dotare il borgo<\/strong> ed in particolare il centro urbano di un nuovo impianto di <strong>video sorveglianza<\/strong> che andr\u00e0 a monitorare, con apparecchiature di ultima generazione, punti attualmente scoperti del territorio.<\/p>\n<p><strong>L&#8217;investimento pi\u00f9 grande<\/strong>, anche in termini di relazione con il comprensorio avviando una sinergia istituzionale e progettuale con i Comuni di <strong>Morano Calabro, Saracena e Orsomarso,<\/strong> \u00e8 invece quello candidato ai Contratti Istituzionali di Sviluppo denominato \u201c<strong>Vivere il Pollino<\/strong>\u201d per un importo superiore a 1milione e 600 mila euro. Una strategia di sviluppo del turismo tramite la valorizzazione del patrimonio esistente, la realizzazione di strutture ricettive, la mobilit\u00e0 sostenibile nell\u2019ambito dell\u2019ospitalit\u00e0 diffusa a servizio del turismo comprensoriale nel borgo dell\u2019architettura e dell\u2019artigianato.<\/p>\n<p>&#8220;Una progettualit\u00e0 che complessivamente candida una proposta di pi\u00f9 di 8 milioni di euro per la quale \u00abla nostra municipalit\u00e0 &#8211; ha spiegato il sindaco <strong>Giuseppe Regina<\/strong> &#8211; \u00e8 stata scelta come capofila. Impegno che ci inorgoglisce e ci responsabilizza ulteriormente volendo realizzare, nell&#8217;interesse delle Comunit\u00e0 coinvolte, il miglior risultato per la crescita e lo sviluppo comune\u00bb. Il sindaco di Mormanno e tutto l&#8217;esecutivo hanno inteso ringraziare l\u2019Ufficio Tecnico Comunale e naturalmente \u00abtutti coloro che direttamente o indirettamente hanno contribuito a raggiungere tali prospettive\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono stati presentati i progetti di riqualificazione del borgo. Il sindaco: &#8220;prosegue l&#8217;incessante lavoro di programmazione integrata con il territorio&#8221;<\/p>\n","protected":false},"author":42,"featured_media":160612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-160611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160611"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160612"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}