{"id":160902,"date":"2021-12-25T16:00:16","date_gmt":"2021-12-25T15:00:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/basta-vittime-sulla-ss106-una-rinnovata-visione-di-territorio-e-possibile\/"},"modified":"2023-01-16T17:45:31","modified_gmt":"2023-01-16T16:45:31","slug":"435545-basta-vittime-sulla-ss106-una-rinnovata-visione-di-territorio-e-possibile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/435545-basta-vittime-sulla-ss106-una-rinnovata-visione-di-territorio-e-possibile\/","title":{"rendered":"Basta Vittime sulla SS106: &#8220;una rinnovata visione di territorio \u00e8 possibile&#8221;"},"content":{"rendered":"<p class=\"v1MsoNormal\">CORIGLIANO ROSSANO (CS) &#8211; L&#8217;Organizzazione di Volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221;, il Comitato &#8220;Magna Graecia&#8221; e l&#8217;Associazione &#8220;Corigliano-Rossano Futura&#8221; organizzano, per luned\u00ec 10 gennaio dalle ore 17:30 alla Sala Rossa del Palazzo San Bernardino a Corigliano-Rossano l&#8217;iniziativa dal titolo: &#8220;<strong>Una nuova S.S.106 in una rinnovata visione di territorio \u00e8 possibile: basta solo volerlo&#8221;.<\/strong><\/p>\n<p class=\"v1MsoNormal\">&#8220;Il nuovo asse di collegamento tra Sibari e Roseto Capo Spulico (Megalotto 3) &#8211; si legge in un nota dell&#8217;Organizzazione di Volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221; &#8211; in corso di costruzione \u00e8 l&#8217;esempio emblematico di <strong>quanto sia concretamente possibile realizzare nuovi tratti ammodernati della Statale 106.<\/strong> L&#8217;iniziativa, a partire da un caso reale ormai sotto gli occhi di tutti, ha l&#8217;intenzione di evidenziare quali sono le complessit\u00e0 legate al processo di ammodernamento della, famigerata e tristemente nota, &#8220;strada della morte&#8221; al fine di pervenire ad una proposta concreta e reale per il territorio a Sud di Sibari compreso tra le aree urbane di Corigliano-Rossano e Crotone. Il tutto per favorire un tracciato stradale armonico, condiviso e funzionale a tutto l&#8217;ambito dell&#8217;Arco Jonico e di facile e coerente raccordo con il Capoluogo di Regione. Scopo dell&#8217;iniziativa, &#8211; conclude la nota &#8211; <strong>\u00e8 la volont\u00e0 di dar vita ad un dibattito aperto,<\/strong> il pi\u00f9 plurale possibile, <strong>da cui poi si auspica possa nascere un documento condiviso ed inclusivo&#8221;<\/strong>.<\/p>\n<p class=\"v1MsoNormal\">Alla manifestazione di pubblico dibattito sono stati invitati il Ministro delle infrastrutture e della mobilit\u00e0 sostenibili, l&#8217;Amministratore di Anas Spa, gli Eurodeputati calabresi, la Rappresentanza parlamentare calabrese, i Consiglieri regionali, il Presidente della Giunta regionale, i Presidenti delle Province di Cosenza e Crotone ed i sindaci dei Comuni di Cassano allo Jonio, Corigliano-Rossano, Crosia, Calopezzati, Pietrapaola, Mandatoriccio, Scala Coeli, Cariati, Crucoli, Cir\u00f2, Cir\u00f2 Marina, Strongoli, Melissa, Rocca di Neto, Crotone ed Isola di Capo Rizzuto, nonch\u00e9 gli Amministratori delle Comunit\u00e0 dell&#8217;Area interna compresa tra le valli del Trionto e quella del Neto, insieme ai Presidenti delle Camere di Commercio, Confcommercio, Confesercenti, Cia, Coldiretti, Confagricoltura, Confindustria, Uil, CGIL, Cisl delle Province di Cosenza e Crotone.<\/p>\n<p class=\"v1MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il collegamento tra Sibari e Roseto Capo Spulico \u00e8 l&#8217;esempio di quanto sia possibile realizzare nuovi tratti ammodernati della Statale 106&#8221;<\/p>\n","protected":false},"author":61,"featured_media":160903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-160902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160902"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160903"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}