{"id":160934,"date":"2021-12-22T07:23:22","date_gmt":"2021-12-22T06:23:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-progetto-del-nuovo-cannavino-sconosciuto-ai-sindaci\/"},"modified":"2023-01-16T17:45:34","modified_gmt":"2023-01-16T16:45:34","slug":"435618-il-progetto-del-nuovo-cannavino-sconosciuto-ai-sindaci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/435618-il-progetto-del-nuovo-cannavino-sconosciuto-ai-sindaci\/","title":{"rendered":"Il progetto del nuovo Cannavino &#8216;sconosciuto&#8217; ai sindaci"},"content":{"rendered":"<p>COSENZA &#8211; Campate in acciaio\/calcestruzzo che affiancheranno quello esistente. L&#8217;Anas ha realizzato una bozza di progetto che prevede una volta realizzata la nuova opera, la demolizione del Viadotto esistente, mantenendo cos\u00ec una conformazione dei luoghi sostanzialmente analoga a quella esistente. Secondo il progetto di Anas i <strong>vantaggi<\/strong> della soluzione proposta consistono nel garantire la continuit\u00e0 della circolazione lungo la S.S. 107 durante l\u2019esecuzione dei lavori, evitando cos\u00ec i pesanti disagi alle attivit\u00e0 commerciali e turistiche dell\u2019entroterra silano. <strong>La nuova opera sar\u00e0 adeguata alle norme sismiche e progettata con una vita utile doppia<\/strong> (100 anni) rispetto a quello di un\u2019opera \u201cadeguata\u201d o che utilizza parte di strutture esistenti.<\/p>\n<p>Il progetto di Anas prevede ancora il <strong>ripristino della planarit\u00e0 del tracciato<\/strong>, difficilmente recuperabile con un intervento di risanamento della struttura attuale. Anas ha inviato a novembre al <a href=\"https:\/\/quicosenza.it\/news\/14232\" target=\"_blank\" rel=\"noopener\">Ministero dell&#8217;Ambiente<\/a> il progetto della nuova opera affinch\u00e9 venga sottoposto alla valutazione preliminare VIA in linea con la normativa ambientale vigente in materia.<\/p>\n<p>Intanto ieri i <a href=\"https:\/\/quicosenza.it\/news\/14235\" target=\"_blank\" rel=\"noopener\">sindaci hanno trasmesso una richiesta ad Anas<\/a> per chiedere la convocazione di un tavolo tecnico in merito alla nuova realizzazione dell\u2019opera che collega l\u2019area urbana cosentina e la Sila e che ricade sulla strada statale 107 Silana-Crotonese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizzare il nuovo viadotto di fianco a quello attualmente presente che poi sar\u00e0 demolito. Il progetto \u00e8 in fase di redazione<\/p>\n","protected":false},"author":42,"featured_media":160935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-160934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160934"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160935"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}