{"id":160938,"date":"2021-12-22T08:30:55","date_gmt":"2021-12-22T07:30:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/i-nas-scoprono-308-medici-e-operatori-sanitari-no-vax\/"},"modified":"2023-01-16T17:45:34","modified_gmt":"2023-01-16T16:45:34","slug":"435624-i-nas-scoprono-308-medici-e-operatori-sanitari-no-vax","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/435624-i-nas-scoprono-308-medici-e-operatori-sanitari-no-vax\/","title":{"rendered":"I Nas scoprono 308 medici e operatori sanitari no vax"},"content":{"rendered":"<p>ROMA &#8211; Da novembre ad oggi i carabinieri dei Nas hanno <strong>scoperto 308 medici e operatori sanitari non vaccinati irregolarmente al lavoro.<\/strong> Durante i servizi di controllo, i militari hanno monitorato 6.600 posizioni. <strong>Deferiti alle procure 135 tra medici, odontoiatri, farmacisti, infermieri e altre figure<\/strong> ritenute responsabili di esercizio abusivo della professione per aver proseguito lo svolgimento delle proprie attivit\u00e0 nonostante fossero oggetto di provvedimenti di sospensione. Eseguite anche chiusure e sequestri di 6 studi medici e dentistici nonch\u00e9 di 2 farmacie, al cui interno svolgevano l&#8217;attivit\u00e0 professionisti gi\u00e0 sospesi.<\/p>\n<p>Durante l&#8217;attivit\u00e0 investigativa, i carabinieri hanno <strong>sequestrato anche farmaci e dispositivi medici<\/strong> fraudolentemente utilizzati nel corso di attivit\u00e0 e pratiche mediche da parte di soggetti non aventi titolo alla loro detenzione ed impiego.<\/p>\n<p>Il lavoro dei Nas proseguir\u00e0 con ulteriori servizi di controllo sull&#8217;osservanza delle varie tipologie di Green pass ed il rispetto degli obblighi vaccinali. Le operazioni che hanno portato all&#8217;identificazioni di medici e sanitari non vaccinati al lavoro hanno riguardato in particolare Piemonte, Sicilia, Trentino, Emilia-Romagna, Veneto e Campania.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlli dei carabinieri in tutta Italia. Deferiti alle procure 135 tra medici, odontoiatri, farmacisti, infermieri<\/p>\n","protected":false},"author":63,"featured_media":160939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-160938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=160938"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/160938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/160939"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=160938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=160938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=160938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}