{"id":161199,"date":"2021-12-28T10:58:20","date_gmt":"2021-12-28T09:58:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-file-al-centro-di-via-degli-stadi-per-vaccini-e-tamponi\/"},"modified":"2023-01-16T17:45:52","modified_gmt":"2023-01-16T16:45:52","slug":"436266-cosenza-file-al-centro-di-via-degli-stadi-per-vaccini-e-tamponi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/436266-cosenza-file-al-centro-di-via-degli-stadi-per-vaccini-e-tamponi\/","title":{"rendered":"Cosenza, file al centro di via degli Stadi per vaccini e tamponi"},"content":{"rendered":"<p>COSENZA &#8211; Preso d&#8217;assalto il centro vaccinale che ha sede nel Palazzetto delle Associazioni in via degli Stadi dove questa mattina si registrano lunghe file di cittadini in attesa di ricevere la somministrazione del vaccino anti Covid 19. Decine di persone infatti, sono in coda da stamattina per l&#8217;inoculazione della dose e <strong>non sono mancati momenti di tensione.\u00a0<\/strong><\/p>\n<p>Non passa inosservata neanche la lunga fila per <strong>sottoporsi al tampone molecolare che avviene con la formula del drive in<\/strong>. Il fenomeno \u00e8 certamente legato alle numerose occasioni di ritrovo delle festivit\u00e0 natalizie, con parenti e amici, che hanno generato un aumento dei casi di positivit\u00e0.<strong> Solo questa mattina sono stati gi\u00e0 eseguiti circa 200 tamponi.\u00a0<\/strong><\/p>\n<p>Nel weekend natalizio sono state prese d&#8217;assalto anche le farmacie della citt\u00e0 e dell&#8217;area urbana dove, gi\u00e0 dalla mattinata del 24 dicembre, in alcune attivit\u00e0 erano persino terminati i test antigenici.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-436287 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/12\/fila-drive-in-tamponi-cosenza-via-stadi.jpg\" alt=\"\" width=\"572\" height=\"346\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-436288 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/12\/Tamponi-covid-stadi-cosenza-drive-in.jpg\" alt=\"\" width=\"581\" height=\"351\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-436267 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/12\/fila-via-degli-stadi-covid-vaccini-cosenza-01.jpg\" alt=\"\" width=\"589\" height=\"343\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-436279 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/12\/fila-tamponi-drive-in-cosenza-via-stadi-01.jpg\" alt=\"\" width=\"593\" height=\"367\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-436281 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/12\/via-degli-stadi-covid-tamponi-cosenza-03.jpg\" alt=\"\" width=\"596\" height=\"367\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel weekend natalizio sono state prese d&#8217;assalto anche le farmacie della citt\u00e0. Lunghe code stamattina per i tamponi ma anche per i vaccini<\/p>\n","protected":false},"author":42,"featured_media":161200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-161199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=161199"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/161200"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=161199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=161199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=161199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}