{"id":161201,"date":"2021-12-28T10:30:37","date_gmt":"2021-12-28T09:30:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arrestata-per-spaccio-di-droga-nella-sua-casa-di-montalto\/"},"modified":"2023-01-16T17:45:52","modified_gmt":"2023-01-16T16:45:52","slug":"436269-arrestata-per-spaccio-di-droga-nella-sua-casa-di-montalto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/436269-arrestata-per-spaccio-di-droga-nella-sua-casa-di-montalto\/","title":{"rendered":"Arrestata per spaccio di droga nella sua casa di Montalto"},"content":{"rendered":"<p>MONTALTO &#8211; I carabinieri del Comando provinciale di Cosenza, nell\u2019ambito di un servizio di controllo del territorio di Montalto Uffugo, hanno tratto in arresto, in flagranza di reato, una 36enne per il reato di detenzione ai fini di<strong> spaccio di sostanze stupefacenti<\/strong>. <\/p>\n<p>I militari, all\u2019esito di una perquisizione domiciliare, svolta presso l\u2019abitazione della donna, hanno rinvenuto <strong>55 grammi <\/strong>di sostanza stupefacente del tipo <strong>marijuana<\/strong>, <strong>2,07 grammi<\/strong> di sostanza stupefacente del tipo <strong>hashish <\/strong>ed un bilancino di precisione. <\/p>\n<p>Nel corso dell\u2019attivit\u00e0 di perquisizione \u00e8 stata, inoltre, rinvenuta e sequestrata <strong>una rilevante somma in contanti<\/strong>, suddivisa in banconote di piccolo taglio, provento della pregressa e connessa attivit\u00e0 di spaccio. <\/p>\n<p>I carabinieri hanno quindi posto la donna presso la propria abitazione in regime di arresti domiciliari, in attesa del rito direttissimo, cos\u00ec come disposto dall\u2019autorit\u00e0 giudiziaria di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna \u00e8 stata sorpresa dai carabinieri con stupefacenti e con una ingente somma di contanti<\/p>\n","protected":false},"author":63,"featured_media":161202,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-161201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=161201"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/161202"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=161201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=161201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=161201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}