{"id":161463,"date":"2022-01-02T17:00:14","date_gmt":"2022-01-02T16:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/camper-in-fiamme-alla-pompa-di-benzina\/"},"modified":"2023-01-16T16:57:00","modified_gmt":"2023-01-16T15:57:00","slug":"436806-camper-in-fiamme-alla-pompa-di-benzina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/436806-camper-in-fiamme-alla-pompa-di-benzina\/","title":{"rendered":"Camper in fiamme alla pompa di benzina"},"content":{"rendered":"<p>CIRO&#8217; MARINA &#8211; Disavventura per i passeggeri di un Camper nel Comune di Cir\u00f2 Marina. Alle ore 16 circa una squadra dei vigili del fuoco del comando provinciale di Crotone, distaccamento di Cir\u00f2 Marina, \u00e8 intervenuta per l&#8217;incedio di un camper presso un distributore di benzina. <\/p>\n<p>A bordo del mezzo un nucleo familiare che, mentre faceva rifornimento, ha visto le fiamme partire dal vano motore. Il tempestivo intervento dei vigili del fuoco \u00e8 valso alla completa estinzione del rogo evitando il propagarsi all&#8217;intero veicolo ed alla messa in sicurezza del sito.<\/p>\n<p>Tanta paura tra i passeggeri che in attesa dei soccorritori si allontanavo in zona sicura. Non si registrano danni a persone. Origine dell&#8217;incendio un probabile malfunzionamento dell&#8217;impianto elettrico del camper.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Origine dell&#8217;incendio un probabile malfunzionamento dell&#8217;impianto elettrico del camper, salvi i passeggeri<\/p>\n","protected":false},"author":63,"featured_media":161464,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-161463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=161463"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/161464"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=161463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=161463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=161463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}