{"id":161594,"date":"2022-01-05T09:05:55","date_gmt":"2022-01-05T08:05:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-sette-indagati-per-la-morte-di-giampiero-tarasi\/"},"modified":"2023-01-16T16:57:08","modified_gmt":"2023-01-16T15:57:08","slug":"437091-cosenza-sette-indagati-per-la-morte-di-giampiero-tarasi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/437091-cosenza-sette-indagati-per-la-morte-di-giampiero-tarasi\/","title":{"rendered":"Cosenza, sette indagati per la morte di Giampiero Tarasi"},"content":{"rendered":"<p>COSENZA &#8211; Si schianta in moto contro il guard rail\u00a0 <strong>Giampiero Tarasi<\/strong>, 33 anni, lo scorso 8 marzo. A bordo della sua Ducati contro le barriere di cemento posizionate su corso Vittorio Emanuele nella zona di Portapiana, <strong>in un tratto senza illuminazione e soprattutto senza alcuna segnalazione<\/strong> che indicasse la presenza di quelle maledette new jersey posizionate per mesi in seguito a una frana. Una morte che ha lasciato nel dolore straziante e nella disperazione i familiari, la fidanzata Federica e gli amici che descrivono Giampiero come una persona estremamente buona, alla quale era impossibile trovare un difetto. Inutile l&#8217;intervento dei sanitari del 118 che, arrivati sul posto hanno potuto costatare solo il decesso del giovane.<\/p>\n<p>La citt\u00e0 di Cosenza, a distanza di mesi non si d\u00e0 pace per la prematura scomparsa del centauro. La procura diretta da <span style=\"font-weight: 700 !important;\">Mario Spagnuolo<\/span> ha avviato un\u2019inchiesta per accertare se fossero state adottate tutte le misure precauzionali e di sicurezza per segnalare la presenza delle barriere in cemento. Le indagini si sono concluse ipotizzando delle rilevati negligenze che potrebbero essere ritenute fatali per la morte di Tarasi, indagini che sono state coordinate dal pm <span style=\"font-weight: 700 !important;\">Bianca Maria Battini.\u00a0<\/span><\/p>\n<p><strong>A sette persone<\/strong> \u00e8 stato notificato l\u2019avviso di conclusione delle indagini preliminari in merito alla morte di Giampiero Tarasi. Nel registro degli indagati sono stati iscritti<strong> Antonella Rino<\/strong> (dirigente del Comune di Cosenza settore II manutenzione ordinaria-protezione civile-datore di lavoro); <strong>Ettore Tucci<\/strong> (responsabile unico del procedimento tecnico); <strong>Giuseppe Bruno<\/strong> (comandante Polizia municipale di Cosenza in carica dal 24.7.2019 al 29.1.2020);<strong> Agostino Rosselli<\/strong> (comandante Polizia municipale di Cosenza dal 30.l.2020 al 28.7.2020); <strong>Alessia Loise<\/strong> (comandante Polizia municipale di Cosenza dal 29 luglio 2020 ad oggi) e due imprenditori <strong>Robertino Perri e Pasquale Perri. <\/strong><\/p>\n<p>Agli indagati viene imputato <strong>di non aver garantito la sicurezza sul tratto stradale <\/strong>di corso Vittorio Emanuele nella zona di Portapiana e di non aver apposto<strong> l\u2019opportuna segnaletica di cantiere prevista dalla legge.<\/strong> Gli indagati ora, avranno 20 giorni di tempo per produrre memorie difensive e chiedere di essere sentiti dal magistrato. Le persone indagate <strong>sono da ritenersi innocenti fino ad eventuale sentenza di condanna passata in giudicato.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attualmente gli indagati sono: 5 dirigenti comunali e 2 imprenditori\u00a0accusati di non aver garantito la sicurezza sul tratto stradale<\/p>\n","protected":false},"author":61,"featured_media":161595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-161594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=161594"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/161595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=161594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=161594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=161594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}