{"id":161735,"date":"2022-01-07T17:15:09","date_gmt":"2022-01-07T16:15:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-centro-calabrese-di-solidarieta-cerca-docenti-ed-educatori-ecco-le-lauree-richieste\/"},"modified":"2023-01-16T16:57:18","modified_gmt":"2023-01-16T15:57:18","slug":"437429-il-centro-calabrese-di-solidarieta-cerca-docenti-ed-educatori-ecco-le-lauree-richieste","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/437429-il-centro-calabrese-di-solidarieta-cerca-docenti-ed-educatori-ecco-le-lauree-richieste\/","title":{"rendered":"Il Centro Calabrese di Solidariet\u00e0 cerca docenti ed educatori. Ecco le lauree richieste"},"content":{"rendered":"<p class=\"v1MsoNormal\">CATANZARO &#8211; Il<a href=\"https:\/\/quicosenza.it\/news\/14293\" target=\"_blank\" rel=\"noopener\"> Centro Calabrese di Solidariet\u00e0<\/a> a Catanzaro \u00e8 alla ricerca di <strong>docenti ed educatori\/educatrici<\/strong> che saranno coinvolti nello svolgimento di attivit\u00e0 di insegnamento in orario pomeridiano, attraverso percorsi personalizzati di supporto scolastico gratuiti, dedicati a studenti e studentesse di et\u00e0 compresa tra i 12 e i 17 anni.<\/p>\n<p class=\"v1MsoNormal\">I termini per l&#8217;invio della lettera motivazionale e il curriculum (massimo tre pagine) <strong>scadono luned\u00ec 10 gennaio<\/strong>. La lettera pu\u00f2 essere inviata all&#8217;indirizzo:\u00a0<a href=\"mailto:prevenzione@ccscatanzaro.it\" rel=\"noreferrer\">prevenzione@ccscatanzaro.it<\/a><\/p>\n<p class=\"v1MsoNormal\"><strong>Il requisito principale per candidarsi \u00e8 il possesso di una certificazione di laurea in uno dei seguenti<\/strong><\/p>\n<p class=\"v1MsoNormal\">ambiti:<strong> Scientifico<\/strong> (soprattutto per aiutare nello studio di matematica, fisica e scienze); Umanistico (soprattutto per aiutare nello studio di italiano, latino, geostoria e filosofia); <strong>Linguistico<\/strong> (soprattutto per aiutare nello studio di italiano e inglese); <strong>Educativo e pedagogico<\/strong>.<\/p>\n<p class=\"v1MsoNormal\"><span class=\"v1gmail-fontstyle01\">Altri criteri\u00a0<\/span><span class=\"v1gmail-fontstyle21\">di valutazione saranno:<\/span>\u00a0<span class=\"v1gmail-fontstyle01\">Per docenti<\/span><span class=\"v1gmail-fontstyle21\">, esperienze nell&#8217;ambito dell&#8217;insegnamento uno a uno e capacit\u00e0 di lavorare con<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">studenti\/studentesse con <strong>BES o DSA<\/strong>; competenza ed esperienza nella didattica a distanza e<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">nell&#8217;uso di strumenti digitali educativi; capacit\u00e0 di insegnare altre materie oltre a quelle<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">specificamente richieste.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span class=\"v1gmail-fontstyle01\">Per<strong> educatori<\/strong><\/span><span class=\"v1gmail-fontstyle21\">, capacit\u00e0 di approcciare l&#8217;insegnamento di alcune discipline (p.e. italiano o<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">matematica); capacit\u00e0 di organizzare un lavoro a distanza con gli studenti ricorrendo a diversi<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">metodi; capacit\u00e0 di lavorare con studenti con BES o DSA.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span class=\"v1gmail-fontstyle21\">I <\/span><span class=\"v1gmail-fontstyle01\">candidati\u00a0<\/span><span class=\"v1gmail-fontstyle21\">ritenuti idonei verranno contattati e convocati per sostenere le\u00a0<\/span><span class=\"v1gmail-fontstyle01\">selezioni. <\/span><span class=\"v1gmail-fontstyle21\"><strong>L&#8217;impegno previsto \u00e8 di 23 ore settimanali<\/strong> da svolgersi prevalentemente in orario pomeridiano. <\/span><span class=\"v1gmail-fontstyle21\">I candidati che saranno convocati per le selezioni e per lo svolgimento degli incarichi dovranno<\/span>\u00a0<span class=\"v1gmail-fontstyle21\">essere muniti di green pass.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Centro Calabrese di Solidariet\u00e0 \u00e8 alla ricerca di docenti ed educatori\/educatrici che saranno coinvolti nello svolgimento di attivit\u00e0 di insegnamento in orario pomeridiano<\/p>\n","protected":false},"author":58,"featured_media":161736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-161735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=161735"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/161735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/161736"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=161735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=161735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=161735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}