{"id":162003,"date":"2022-01-16T16:00:16","date_gmt":"2022-01-16T15:00:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/donne-vittime-di-violenza-incentivi-alle-imprese-se-assumono\/"},"modified":"2023-01-16T16:57:35","modified_gmt":"2023-01-16T15:57:35","slug":"438016-donne-vittime-di-violenza-incentivi-alle-imprese-se-assumono","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/438016-donne-vittime-di-violenza-incentivi-alle-imprese-se-assumono\/","title":{"rendered":"Donne vittime di violenza &#8220;incentivi alle imprese se assumono&#8221;"},"content":{"rendered":"<p>ROMA &#8211; &#8220;E&#8217; un dato indiscutibile che in una <strong>situazione di violenza la difficolt\u00e0 economica aggravia la situazion<\/strong>e. Riteniamo importante sostenere le donne dopo che hanno trovato la forza di denunciare e siamo a favore della realizzazione di criteri per agevolare il loro ingresso o reingresso nel mondo lavorativo&#8221;. Lo ha detto la videpresidente di <strong>Telefono Rosa<\/strong> Antonella Faieta in Commissione Lavoro, nell&#8217;ambito dell&#8217;esame delle proposte di legge recanti disposizioni per l&#8217;inserimento lavorativo delle donne vittime di violenza di genere.<\/p>\n<p>&#8220;La prospettiva di poter lavorare sar\u00e0 di<strong> stimolo alle donne<\/strong> che si sentono ingabbiate in una relazione violenta &#8211; ha aggiunto &#8211; Ma, in merito alle proposte di legge, le beneficiarie non possono essere solo le vittime di violenza domestica. Anche le imprese devono avere incentivi se assumono donne vittime di violenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo ha chiesto la videpresidente di Telefono Rosa Antonella Faieta in Commissione Lavoro, nell&#8217;ambito dell&#8217;esame delle proposte di legge<\/p>\n","protected":false},"author":58,"featured_media":162004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-162003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162003"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162004"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}