{"id":162060,"date":"2022-01-13T12:18:50","date_gmt":"2022-01-13T11:18:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-e-scuola-sindaci-no-alla-dad-si-al-potenziamento-dei-trasporti\/"},"modified":"2023-01-16T16:57:39","modified_gmt":"2023-01-16T15:57:39","slug":"438148-covid-e-scuola-sindaci-no-alla-dad-si-al-potenziamento-dei-trasporti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/438148-covid-e-scuola-sindaci-no-alla-dad-si-al-potenziamento-dei-trasporti\/","title":{"rendered":"Covid e scuola, sindaci vanno avanti &#8220;No alla Dad ma potenziare i trasporti&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Si sono riuniti i sindaci di Catanzaro, <strong>Cosenza<\/strong>, Crotone, Vibo Valentia, Corigliano-Rossano, Lamezia Terme e <strong>Rende<\/strong> per un esame della situazione e al termine del confronto \u00e8 emersa la loro <strong>netta contrariet\u00e0 alla didattica a distanza<\/strong>. Il tavolo permanente si \u00e8 riunito ieri per monitorare e confrontarsi sull&#8217;evoluzione dell&#8217;emergenza pandemica anche in relazione alla ripresa della didattica in presenza sancita dal Governo.<\/p>\n<p>I sidnaci hanno confermato unanimemente la linea gi\u00e0 stabilita nel corso della riunione di <strong>sabato scorso<\/strong>, &#8220;giudicando ineludibile nel contesto attuale &#8211; in assenza di un diverso provvedimento governativo &#8211; lo svolgimento della didattica in presenza. Questa decisione &#8211; si sottolinea &#8211; tiene conto della delicata esigenza di contemperare il diritto alla salute ed il diritto allo studio, ed in particolare \u00e8 finalizzata ad evitare di alterare ulteriormente il percorso didattico di alunni e studenti, gi\u00e0 reso piuttosto accidentato dall&#8217;emergenza pandemica che ormai permane da quasi due anni&#8221;.<\/p>\n<p>I sindaci inoltre &#8220;hanno condiviso il fatto che<strong> una delle principali criticit\u00e0 di questa fase \u00e8 rappresentata dal trasporto pubblico<\/strong>, ovvero dalla concentrazione di molti studenti sui mezzi pubblici di collegamento con gli istituti scolastici superiori, col rischio quindi di dare vita ad assembramenti pericolosi ai fini del contenimento virale&#8221;. Per questa ragione <strong>sar\u00e0 richiesto alla Regione Calabria &#8220;di intervenire<\/strong> per superare con urgenza tali criticit\u00e0, contemplando la possibilit\u00e0 di aumentare le corse del trasporto pubblico locale finalizzate al collegamento con gli istituti scolastici e fornendo alla comunit\u00e0 studentesca le mascherine FFP2 che \u00e8 necessario indossare su gran parte dei mezzi pubblici&#8221;. Il tavolo rileva che, &#8220;a due anni dall&#8217;inizio della pandemia, una delle difficolt\u00e0 principali della gestione pandemica che grava sui comuni \u00e8 quella della notifica delle ordinanze di quarantena e di revoca, che hanno ormai monopolizzato alcuni dei servizi comunali&#8221;.<\/p>\n<p>A tal proposito, &#8220;prendendo atto della utile semplificazione prevista gi\u00e0 dall&#8217;ordinanza del Presidente della Regione n. 5 del 10 Gennaio, tenuto conto del fatto che in altre regioni gli enti comunali sono esonerati da tale compito svolto direttamente dalle Aziende Sanitarie&#8221;, si \u00e8 deciso di proporre ad Anci Calabria di farsi promotrice di una iniziativa di sensibilizzazione nei confronti del Presidente della Regione, finalizzata all&#8217; adozione di un provvedimento che semplifichi ulteriormente tale procedura, ritenendo insostenibile l&#8217;attuale carico di lavoro dei comuni. <strong>Il tavolo permanente si riunir\u00e0 nuovamente sabato 15 gennaio. <\/strong><\/p>\n<p>Il documento \u00e8 firmato da Sergio Abramo, sindaco di Catanzaro Flavio Stasi, sindaco di Corigliano-Rossano, Franz Caruso, sindaco di Cosenza, Vincenzo Voce, sindaco di Crotone, Paolo Mascaro, sindaco di Lamezia Terme, Marcello Manna, sindaco di Rende, Maria Limardo, sindaco di Vibo Valentia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le scuole devono riaprire  le porte agli studenti. E&#8217; questa la posizione dei sindaci delle principali citt\u00e0 calabresi tra cui Franz Caruso, primo cittadino di Cosenza<\/p>\n","protected":false},"author":42,"featured_media":162061,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-162060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162060"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162061"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}