{"id":16208,"date":"2013-01-21T16:25:39","date_gmt":"2013-01-21T15:25:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16208"},"modified":"2023-01-17T13:14:18","modified_gmt":"2023-01-17T12:14:18","slug":"5530-al-via-lavori-campo-di-calcetto-a-farina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5530-al-via-lavori-campo-di-calcetto-a-farina\/","title":{"rendered":"Al via lavori campo di calcetto a &#8220;Farina&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CROTONE<\/strong> &#8211; &nbsp;Una buona notizia per gli abitanti, ma soprattutto i ragazzi del popolare quartiere di Farina a Crotone: il prossimo 28 gennaio, avranno inizio i<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">lavori per la realizzazione di un campo di calcetto a loro destinato. A darne notizia \u00e8 l&#8217;assessore comunale allo sport ed ai quartieri Claudio Mole&#8217; Il campetto che sorgera&#8217; in prossimita&#8217; della Chiesa di S. Maria, sara&#8217; realizzato in erbetta sintetica della dimensione dell&#8217;area di gioca pari a metri 20&#215;40, dotato di rete di protezione esterna. Un progetto che rientra nella programmazione PISU (Programma Integrato di Sviluppo Urbano) per il quale l&#8217;amministrazione investe oltre 110.000 euro.&nbsp;&nbsp;&#8220;L&#8217;obiettivo dell&#8217;amministrazione Vallone&#8221; dichiara l&#8217;assessore allo Sport ed ai Quartieri Claudio Mole&#8217; &#8220;e&#8217; quello incentivare l&#8217;aggregazione giovanile e offrire strutture adeguate per il tempo libero ai residenti nel quartiere Farina ed in particolare ai giovani&#8221;. Un quartiere che sta crescendo, quello di Farina, dopo la realizzazione da parte dell&#8217;amministrazione comunale di Via Nazioni Unite, oltre tre chilometri di strada completa di sottoservizi, e l&#8217;avvio dei lavori per la costruzione del nuovo asilo comunale. &#8220;Questa nuova opera&#8221; prosegue l&#8217;assessore Mole&#8217; &#8220;si aggiunge alle attivita&#8217; messe in campo dall&#8217;amministrazione per trasformare quartieri dormitorio in quartieri vivibili dotati di strutture in grado di favorire la socializzazione&#8221;. Attivita&#8217; che guardano anche alle famiglie: non a caso l&#8217;amministrazione Vallone ha portato nel quartiere il gas metano oltre che per fornire un servizio anche per contribuire ad un abbattimento dei costi per i nuclei familiari che abitano nella zona. Ed il campetto che presto sara&#8217; realizzato e che sara&#8217; dato in comodato d&#8217;uso alla parrocchia che gia&#8217; svolge un lavoro egregio con i giovani, sara&#8217; un ulteriore elemento di crescita per la vivibilita&#8217; del quartiere Farina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; &nbsp;Una buona notizia per gli abitanti, ma soprattutto i ragazzi del popolare quartiere di Farina a Crotone: il prossimo 28 gennaio, avranno inizio i<\/p>\n","protected":false},"author":22,"featured_media":16209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-16208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16208"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16209"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}