{"id":162116,"date":"2022-01-14T09:05:14","date_gmt":"2022-01-14T08:05:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-visite-vietate-ai-pazienti-in-ospedale-falsetta-non-diventi-prassi\/"},"modified":"2023-01-16T16:57:42","modified_gmt":"2023-01-16T15:57:42","slug":"438281-cosenza-visite-vietate-ai-pazienti-in-ospedale-falsetta-non-diventi-prassi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/438281-cosenza-visite-vietate-ai-pazienti-in-ospedale-falsetta-non-diventi-prassi\/","title":{"rendered":"Cosenza, visite vietate ai pazienti in ospedale. Falsetta: &#8220;non diventi prassi&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; \u201cPerch\u00e8 non possiamo assistere i nostri cari, No Covid, in ospedale?\u201d. Qualche giorno fa <a href=\"https:\/\/quicosenza.it\/news\/14335\" target=\"_blank\" rel=\"noopener\">ha scritto alla nostra redazione un cittadino<\/a> che ha voluto rivolgere un appello al presidente Occhiuto per ovviare a questa situazione che dopo due anni di pandemia vede costrette alla solitudine le persone nei pronto soccorso: &#8220;ancora oggi, nessun familiare pu\u00f2 stargli vicino anche se non hanno il Covid\u201d. Un appello rilanciato oggi dalla presidente dell&#8217;associazione Bene Comune Calabria, Falsetta, che chiede al presidente della Regione di prendere gli opportuni provvedimenti affinch\u00e8 i familiari possano ritornare ad essere vicini ai propri cari in ospedale, prestando loro assistenza e, senza trascurare, naturalmente, le necessarie precauzioni.<\/p>\n<p>&#8220;Il <strong>ricovero in ospedale<\/strong> \u2013 spiega la presidente Falsetta &#8211; rappresenta per qualunque persona un momento di ansia, di paura, di estraneit\u00e0 rispetto al proprio ambiente di vita, per cui la lontananza dalla famiglia non fa altro che accentuarne le sofferenze. Non solo. Ritengo che<strong> la situazione di impossibilit\u00e0 di accesso dei parenti all\u2019interno del nosocomio non possa continuare a rimanere la stessa ancora oggi<\/strong>, come se fossimo agli inizi della pandemia, in quanto questa situazione di stallo spinge sempre di pi\u00f9 verso la <strong>completa assenza di relazioni e di confronto con i medici ed il personale sanitario,<\/strong> indispensabile per vigilare sull\u2019esperienza vissuta dai propri cari presso la struttura di ricovero, nonch\u00e8 sull\u2019organizzazione dei servizi in un contesto in cui debbano prevalere criteri di efficienza e di uso responsabile delle risorse&#8221;.<\/p>\n<p>&#8220;Questo significa che &#8211; prosegue &#8211; specie di fronte ad un\u2019organizzazione complessa come quella sanitaria calabrese, i <strong>familiari dei pazienti non possono in nessun caso essere estromessi<\/strong>, in quanto hanno il sacrosanto ed inviolabile \u201cdiritto-dovere\u201d di partecipare attivamente alla vita del paziente, di rendersi conto di persona di ci\u00f2 che accade all\u2019interno della struttura di ricovero, di informarsi costantemente sullo stato di salute dei propri congiunti attraverso un \u201c<strong>confronto diretto<\/strong>\u201d con i medici ed il personale sanitario, di \u201cmonitorare\u201d eventuali inefficienze organizzative o disagi, dal momento dell\u2019accoglienza fino alla dimissione&#8221;.<\/p>\n<p>&#8220;Quanto sta accadendo ci fa comprendere che, in assenza di una gestione razionale dei territori, che sia in grado di rapportarsi in modo adeguato e dinamico di fronte alle emergenze, si finir\u00e0 per favorire il consolidamento di prassi che, invece, dovrebbero essere completamente estranee ad uno Stato di diritto, o quanto meno momentanee, e, comunque, strettamente commisurate alla gravit\u00e0 dello stato emergenziale. Ancora oggi, impedire ai congiunti dei pazienti di instaurare quel sistema di relazioni nell\u2019interesse dei propri cari con i medici ed il personale sanitario, badando esclusivamente ai meri adempimenti burocratici, non ha alcun senso logico. Il mio appello \u2013 conclude Falsetta &#8211; al pari di quello del cittadino che ha sollevato la faccenda, \u00e8 al presidente della Regione Roberto <strong>Occhiuto<\/strong>, affinch\u00e8 <strong>adotti ogni misura diretta a ristabilire quel sistema di relazioni<\/strong> da parte dei congiunti dei pazienti con i medici ed il personale sanitario. Ci\u00f2 consentir\u00e0 da un lato, ai congiunti di assolvere coscientemente alla cura dei propri cari, e, dall\u2019altro, di responsabilizzare maggiormente il sistema sanitario sulla centralit\u00e0 del paziente, non pi\u00f9 solo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>All&#8217;appello pubblicato su quicosenza nei giorni scorsi, si associa il Presidente dell\u2019Associazione Bene Comune Calabria Filomena Falsetta che si rivolge al presidente della Regione Occhiuto<\/p>\n","protected":false},"author":42,"featured_media":162117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-162116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162116"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162117"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}