{"id":162500,"date":"2022-01-20T14:49:04","date_gmt":"2022-01-20T13:49:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/serrati-i-controlli-ai-green-pass-scattano-denunce-e-multe-per-oltre-10mila-euro\/"},"modified":"2023-01-16T16:58:08","modified_gmt":"2023-01-16T15:58:08","slug":"439245-serrati-i-controlli-ai-green-pass-scattano-denunce-e-multe-per-oltre-10mila-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/439245-serrati-i-controlli-ai-green-pass-scattano-denunce-e-multe-per-oltre-10mila-euro\/","title":{"rendered":"Serrati i controlli ai Green Pass, scattano denunce e multe per oltre 10mila euro"},"content":{"rendered":"<p>TAURIANOVA (RC) &#8211; Continuano i controlli dei Carabinieri della Compagnia di Taurianova, in provincia di Reggio Calabria, finalizzati principalmente a garantire il rispetto delle nuove disposizioni dettate dalla normativa emergenziale in vigore anti &#8211; Covid. Lo scorso weekend sono state circa <strong>60 le attivit\u00e0 di ristorazione controllate<\/strong> dai militari dell\u2019Arma, <strong>170 i controlli al \u201cgreen pass\u201d<\/strong>, riscontrando seppur un generale rispetto delle disposizioni in atto, alcune violazioni.<\/p>\n<p>Nello specifico, a Cittanova, i carabinieri hanno contestato sanzioni amministrative a un <strong>gestore di un ristorante e un avventore<\/strong> poich\u00e9 s<strong>provvisti della certificazione verde<\/strong>.<\/p>\n<p>A Polistena, invece, nell\u2019ambito di servizi finalizzati a controllare<strong> la <em>\u201cmovida\u201d<\/em><\/strong>, ove l\u2019amministrazione comunale ha adottato un\u2019ordinanza volta a regolare gli orari di apertura dei bar e dei locali dove vengono somministrate bevande, nel centro storico, i Carabinieri hanno controllato<strong> oltre 300 persone<\/strong>, 11 delle quali sono state sanzionate poich\u00e8 sprovviste di mascherina in strada e in luoghi affollati.<\/p>\n<p>A Taurianova, inoltre, \u00e8 stato denunciato un<strong> soggetto del posto, poich\u00e9 positivo al covid19<\/strong>, \u00e8 stato trovato fuori dalle mura domestiche, a passeggio per strada.<\/p>\n<h4>Arresti per droga e guida in stato di ebrezza<\/h4>\n<p>Sempre nell\u2019ambito del medesimo contesto operativo, i Carabinieri hanno eseguito un provvedimento di aggravamento della misura cautelare emesso dalla Corte di Appello di Reggio Calabria, nei confronti di un soggetto imputato gi\u00e0 ristretto agli arresti domiciliari a Cittanova per rapina, e arrestato un altro soggetto in flagranza per detenzione ai fini di spaccio di sostanza stupefacente, in quanto trovato in possesso di 13,46 gr. di sostanza stupefacente del tipo marijuana, gi\u00e0 confezionata in dosi, nonch\u00e9 di un bilancino di precisione.<\/p>\n<p>Diversi sono stati anche i controlli alla circolazione stradale, nel cui ambito sono state elevate oltre 20 sanzioni per violazioni al codice della strada, per un importo complessivo di quasi 10.000 Euro.<\/p>\n<p>Denunciati, in ultimo, 3 soggetti perch\u00e9, per guida in stato di ebrezza, risultati con un tasso alcoolemico a seguito di accertamento etilometrico, oltre il limite consentito per legge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano i controlli a ristoranti e movida da parte dei Carabinieri sul territorio per garantire il rispetto delle nuove disposizioni anti Covid<\/p>\n","protected":false},"author":58,"featured_media":162501,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-162500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162500"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162501"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}