{"id":162628,"date":"2022-01-22T10:59:59","date_gmt":"2022-01-22T09:59:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/berlusconi-puo-diventare-presidente-della-repubblica-difficile-ma-non-impossibile\/"},"modified":"2023-01-16T16:58:16","modified_gmt":"2023-01-16T15:58:16","slug":"439544-berlusconi-puo-diventare-presidente-della-repubblica-difficile-ma-non-impossibile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/439544-berlusconi-puo-diventare-presidente-della-repubblica-difficile-ma-non-impossibile\/","title":{"rendered":"Berlusconi pu\u00f2 diventare presidente della Repubblica? Difficile ma non impossibile"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Fiato sospeso per le elezioni del nuovo presidente della Repubblica, che si terranno luned\u00ec 24 gennaio<\/strong>. A tenere sulla corda gli alleati, <strong>Silvio Berlusconi<\/strong> che oggi dovrebbe sciogliere la sua riserva e il centrodestra &#8211; alle 16 &#8211; riunir\u00e0 un vertice.<\/p>\n<p>La domanda che tutti si pongono \u00e8 <strong>&#8220;Berlusconi pu\u00f2 davvero diventare presidente della Repubblica?&#8221;<\/strong>. A bocciare il leader di Forza Italia, per\u00f2, sono in primis i cittadini. Lo ha spiegato Nando Pagnoncelli, con un sondaggio illustrato qualche giorno fa a DiMarted\u00ec. Secondo quanto raccolto da Ipsos, infatti, il 72% degli italiani dice di non gradire Berlusconi al Quirinale.<\/p>\n<p><strong>Il Quirinale dunque, per l&#8217;ex premier, pu\u00f2 riverlarsi un&#8217;impresa difficile ma non impossibile<\/strong>. Se tutto il centrodestra vota compatto ci sarebbero le condizioni per spuntarla alla quarta votazione, \u00e8 il ragionamento che si fa negli ambienti vicini al cavaliere. La speranza del presidente di Fi \u00e8 che <strong>una cinquantina di voti &#8216;extra&#8217; possano uscire fuori<\/strong>, non solo tra i 5 Stelle, ma anche a sinistra. Una convinzione che Berlusconi starebbe accarezzando da giorni: se ognuno nel centrodestra appoggia la sua candidatura, alla fine i voti in pi\u00f9 per arrivare alla maggioranza di 505 ci sarebbero.<\/p>\n<h4>Salvini sprona gli alleati<\/h4>\n<p>Salvini sprona gli alleati lanciando una nota in cui dichiara che &#8220;<strong>La coalizione avr\u00e0 l&#8217;onore e l&#8217;onere di proporre per il Colle una candidatura di alto profilo<\/strong>&#8220;. Il leader della Lega ha visto anche Bossi mentre Renzi ha riunito i grandi elettori di Italia Viva, inclini alla scheda bianca al primo voto. Una quarantina di grandi elettori positivi al Covid potranno votare in un &#8216;drive in&#8217; allestito nel parcheggio della Camera, tra strette misure sanitarie.<\/p>\n<p>Sul tavolo, intanto, ci sono tre ipotesi: <strong>Mario Draghi<\/strong>, i cui destini si intrecciano con quelli del governo, un <strong>Mattarella bis<\/strong>, e poi il nome di <strong>Pier Ferdinando Casini<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A bocciare il leader di Forza Italia, per\u00f2, sono in primis i cittadini. Ma con un centrodestra compatto e dei voti extra, nulla \u00e8 impossibile<\/p>\n","protected":false},"author":58,"featured_media":162629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-162628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162628"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162629"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}