{"id":162700,"date":"2022-01-24T09:00:50","date_gmt":"2022-01-24T08:00:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/assaltano-il-bus-del-palermo-con-caschi-e-bastoni-indentificati-i-responsabili\/"},"modified":"2023-01-16T16:58:21","modified_gmt":"2023-01-16T15:58:21","slug":"439773-assaltano-il-bus-del-palermo-con-caschi-e-bastoni-indentificati-i-responsabili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/439773-assaltano-il-bus-del-palermo-con-caschi-e-bastoni-indentificati-i-responsabili\/","title":{"rendered":"Assaltano il bus del Palermo con caschi e bastoni. Indentificati i responsabili"},"content":{"rendered":"<p>Catanzaro &#8211; Assalto a colpi di caschi e bastoni ai danni del pullman del Palermo,<strong> con la squadra a bordo,<\/strong> a Catanzaro. Il mezzo \u00e8 stato oggetto di un attacco vandalico ieri sera a pochi chilometri dall&#8217;hotel che ospita la squadra rosanero <strong>in trasferta in vista della partita di questa sera alle 21 sul campo della squadra calabrese.<\/strong> Mentre il pullman con la squadra e lo staff a bordo era temporaneamente in sosta in due si sono avvicinati colpendo ripetutamente con caschi e bastoni i vetri e la fiancata del mezzo.<\/p>\n<p>Le stesse persone hanno poi seguito e superato in auto il pullman per poi attenderlo e tornare a colpire ancora, mandando in frantumi una vetrata. A parte il mezzo sul quale sono evidenti i segni <strong>dell&#8217;aggressione, il vetro distrutto e la concitazione del momento, nessuno dei calciatori<\/strong> o dello staff rosanero \u00e8 rimasto ferito. Il Palermo ha gi\u00e0 contattato le autorit\u00e0 competenti per sporgere denuncia.<\/p>\n<p>La Questura di Catanzaro ha individuato i responsabili. <strong>Si tratterebbe di due persone di et\u00e0 compresa tra i 39 ed i 46 anni non riconducibili al mondo della tifoseria giallorossa<\/strong>. Uno di loro conosciuto gi\u00e0 alle forze dell\u2019ordine per i suoi trascorsi nel mondo della droga.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandata in frantumi una vetrata del bus dei calciatori del Palermo. Nessuno dei giocatori o dello staff rosanero \u00e8 rimasto ferito<\/p>\n","protected":false},"author":61,"featured_media":162701,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-162700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162700"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162701"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}