{"id":162753,"date":"2022-01-25T09:27:34","date_gmt":"2022-01-25T08:27:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/centro-storic-senzacqua-cittadini-da-giorni-costretti-a-riempire-bottiglie\/"},"modified":"2023-01-16T16:58:25","modified_gmt":"2023-01-16T15:58:25","slug":"439913-centro-storic-senzacqua-cittadini-da-giorni-costretti-a-riempire-bottiglie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/439913-centro-storic-senzacqua-cittadini-da-giorni-costretti-a-riempire-bottiglie\/","title":{"rendered":"Centro storico senz&#8217;acqua, cittadini da giorni costretti a riempire bottiglie"},"content":{"rendered":"<p>COSENZA &#8211; Sono numerose le segnalazioni arrivate dai residenti del centro storico di Cosenza al servizio tecnico di manutezione del settore idrico e alla Polizia municipale. Da qualche giorno infatti, i cittadini che vivono tra tra <strong>corso Plebscito, via Lungo Crati e corso Telesio<\/strong>, non <strong>hanno un filo d&#8217;acqua<\/strong> nei rubinetti e il disagio maggiore \u00e8 legato non solo ad espletare l&#8217;igiene personale ma anche all&#8217;impossibilit\u00e0 di far <strong>partire le caldaie<\/strong> per i <strong>riscaldamenti<\/strong>.<\/p>\n<p>Dopo le <strong>tante chiamate fatte agli uffici preposti del Comune di Cosenza<\/strong>, solo questa mattina sono arrivate alcune squadre della manutenzione settore idrico per cercare di individuare eventuali perdite che hanno causato da giorni, la totale assenza dell&#8217;acqua nei rubinetti.<\/p>\n<p>I residenti nel frattempo sono <strong>stati costretti (e lo sono ancora),<\/strong> a rifornirsi di <strong>acqua con le bottiglie<\/strong> dalle fontane cittadine o ad acquistarla nei supermercati, ma la maggiore difficolt\u00e0 riguarda proprio i riscaldamenti viste le temperature molto basse. A tal proposito una cittadina \u00e8 stata costretta insieme al marito cardiopatico a trascorrere la notte in un <strong>bed and breakfast<\/strong> della citt\u00e0, perch\u00e8 non poteva sopportare il freddo. Secondo quanto emerso, i tecnici e gli operai sono al lavoro per riparare la perdita identificata durante la mattinata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-439917 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/01\/settore-manutenzione-centro-storico-acqua.jpg\" alt=\"\" width=\"472\" height=\"292\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-439940 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/01\/lavori-condotta-idrica-centro-storico-perdita-cosenza.jpg\" alt=\"\" width=\"476\" height=\"529\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I cittadini di Cosenza da anni sono costretti a convivere con le continue carenze idriche ma quando le temperature sono cos\u00ec basse, diventa davvero difficile affrontare il problema<\/p>\n","protected":false},"author":42,"featured_media":162754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-162753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162753"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162754"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}