{"id":162870,"date":"2022-01-26T17:04:41","date_gmt":"2022-01-26T16:04:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arriva-il-bonus-casalinghe-2022-che-cose-requisiti-e-a-chi-spetta-il-contributo\/"},"modified":"2023-01-16T16:58:32","modified_gmt":"2023-01-16T15:58:32","slug":"440188-arriva-il-bonus-casalinghe-2022-che-cose-requisiti-e-a-chi-spetta-il-contributo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/440188-arriva-il-bonus-casalinghe-2022-che-cose-requisiti-e-a-chi-spetta-il-contributo\/","title":{"rendered":"Arriva il Bonus casalinghe 2022: che cos&#8217;\u00e8, requisiti e a chi spetta il contributo"},"content":{"rendered":"<p>ROMA &#8211; C&#8217;\u00e8 anche il <strong>Bonus casalinghe<\/strong>\u00a0fra i provvedimenti emanati dal governo per l&#8217;anno 2022. Lo scorso 15 dicembre, il Ministero delle Pari Opportunit\u00e0 ha pubblicato un avviso pubblico per comunicare le modalit\u00e0 e i requisiti per accedere al finanziamento. Ecco in cosa consiste:<\/p>\n<p>Il Bonus casalinghe \u00e8 un <strong>contributo per aumentare la formazione<\/strong> e l\u2019inclusione sociale di donne e uomini che svolgono attivit\u00e0 domestica; Ma attenzione non si tratta di un contributo in denaro sotto forma di assegno mensile, bens\u00ec di un <strong>fondo per la formazione digitale<\/strong>;<\/p>\n<p>L&#8217;obiettivo<strong>\u00a0<\/strong>del Bonus casalinghe<strong>\u00a0<\/strong>\u00e8 quello di<strong>\u00a0incrementare le<\/strong>\u00a0<strong>opportunit\u00e0 lavorative<\/strong>\u00a0di persone che in prevalenza svolgono attivit\u00e0, senza vincolo di subordinazione e a titolo gratuito, finalizzate alla cura delle persone e dell\u2019ambiente domestico;\u00a0Per poter accedere al Bonus casalinghe \u00e8 necessario essere iscritti all\u2019Assicurazione obbligatoria per il lavoro svolto in ambito domestico e dunque essere in regola con il pagamento della <strong>polizza assicurativa INAIL contro gli infortuni domestici<\/strong>, in scadenza il 31 gennaio 2022;<\/p>\n<p>Il Bonus \u00e8 collegato al\u00a0<strong>bando, con scadenza al 31 marzo 2022<\/strong>, con cui enti pubblici, privati e associazioni che si occupano di formazione dovranno presentare i progetti che saranno eventualmente ammessi al finanziamento; I suddetti progetti dovranno includere dei corsi di formazione in campo digitale (somministrati in modalit\u00e0 esclusivamente telematica) da realizzarsi in un arco temporale massimo di dodici mesi; Nello specifico, come si legge nel bando, i <strong>corsi del Bonus casalinghe\u00a0<\/strong>si focalizzeranno sull\u2019<strong>acquisizione di conoscenze<\/strong>\u00a0come ricercare informazioni sui vari motori di ricerca, riconoscere le fake news, archiviare dati su piattaforme cloud; creare\u00a0<strong>contenuti digitali\u00a0<\/strong>e imparare semplici regole di copyright; imparare ad utilizzare gli strumenti di comunicazione digitale, come le email, le chat e i social network; installare o disinstallare programmi sul pc, verificare la connessione internet<strong>\u00a0<\/strong>e acquisire un approccio risolutivo ai problemi del computer.<\/p>\n<p>Sono inoltre previsti corsi per implementare le<strong>\u00a0conoscenze sulla sicurezza e la protezione\u00a0<\/strong>di dispositivi, dati e privacy in tutti gli spazi digitali; conoscere i servizi online per il cittadino, a partire dall\u2019utilizzo di\u00a0<strong>SPID<\/strong>, dei pagamenti digitali e delle piattaforme pubbliche quali l\u2019INPS o l\u2019Agenzia delle Entrate; conoscere e gestire strumenti digitali in grado di migliorare l\u2019organizzazione e la gestione del budget domestico.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ministero delle Pari Opportunit\u00e0 ha pubblicato un avviso per comunicare modalit\u00e0 e requisiti del contributo<\/p>\n","protected":false},"author":61,"featured_media":162871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-162870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162870"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162871"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}