{"id":162876,"date":"2022-01-30T06:00:12","date_gmt":"2022-01-30T05:00:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/report-decessi-per-covid-80-anni-eta-media-piu-alta-per-i-vaccinati\/"},"modified":"2023-01-16T16:58:33","modified_gmt":"2023-01-16T15:58:33","slug":"440200-report-decessi-per-covid-80-anni-eta-media-piu-alta-per-i-vaccinati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/440200-report-decessi-per-covid-80-anni-eta-media-piu-alta-per-i-vaccinati\/","title":{"rendered":"Report decessi per Covid &#8220;80 anni et\u00e0 media, pi\u00f9 alta per i vaccinati&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; <strong>L&#8217;et\u00e0 media dei deceduti e positivi a SARS-CoV-2 in Italia \u00e8 di 80 anni<\/strong>, la maggior parte \u00e8 stata ricoverata in ospedale ma non in terapia intensiva e i deceduti vaccinati hanno un&#8217;et\u00e0 media pi\u00f9 alta e pi\u00f9 patologie preesistenti rispetto a quelli non vaccinati. Sono alcuni dei dati emersi dall&#8217;aggiornamento del report decessi, basato sui dati della Sorveglianza Integrata e su un campione di cartelle cliniche di pazienti deceduti con positivit\u00e0 al SARS-CoV-2, appena pubblicato dall&#8217;Istituto superiore di sanit\u00e0 (Iss). (ANSA).<\/p>\n<h4>Report decessi: et\u00e0 e numero di patologie osservate<\/h4>\n<p>Nei pazienti deceduti trasferiti in terapia intensiva, spiega l&#8217;Iss, il numero medio di patologie osservate \u00e8 di 3,0. Nelle persone che non sono state ricoverate in terapia intensiva il numero medio di patologie osservate \u00e8 di 3,9. Inoltre, rileva sempre l&#8217;Iss, &#8220;rispetto ai deceduti &#8216;non vaccinati&#8217;, sia quelli con &#8216;ciclo incompleto di vaccinazione&#8217; che i decessi con &#8216;ciclo completo di vaccinazione&#8217; (non sono presi in considerazione pazienti con &#8216;booster&#8217;) avevano un&#8217;et\u00e0 media notevolmente superiore (rispettivamente 82,6 e 84,7 vs 78,6)&#8221;.<\/p>\n<p>Anche il <strong>numero medio di patologie osservate \u00e8 significativamente pi\u00f9 alto nei gruppi di vaccinati con &#8216;ciclo incompleto di vaccinazione&#8217; e &#8216;ciclo completo di vaccinazione&#8217; rispetto ai &#8216;non vaccinati<\/strong>&#8216; (rispettivamente 5,0 e 4,9 vs 3,9 patologie preesistenti) La sezione dei dati dalla sorveglianza integrata COVID-19 descrive le caratteristiche di 138.099 pazienti deceduti e positivi a SARS-CoV-2 in Italia dall&#8217;inizio della sorveglianza al 10 gennaio 2022 riportati dalla Sorveglianza Integrata COVID-19 coordinata dall&#8217;Istituto Superiore di Sanit\u00e0.<\/p>\n<h4>17% dei decessi per Covid \u00e8 avvenuto in casa<\/h4>\n<p>L&#8217;et\u00e0 media dei pazienti deceduti e positivi a SARS-CoV-2 \u00e8 80 anni e le donne decedute sono 60.201 (43,6%). L&#8217;et\u00e0 mediana dei pazienti deceduti positivi a SARS-CoV-2 \u00e8 pi\u00f9 alta di circa 40 anni rispetto a quella dei pazienti che hanno contratto l&#8217;infezione. Dei deceduti positivi a SARS-CoV-2 in Italia, il <strong>23,8% risulta essere stato ricoverato in un reparto di terapia intensiva<\/strong>, il <strong>58,5% \u00e8 stato ricoverato in ospedale<\/strong> ma non in terapia intensiva ed il <strong>17,7% non era ricoverato in ospedale<\/strong>.<\/p>\n<p>I dati ottenuti da un campione di cartelle cliniche sono stati ottenuti da 8.436 deceduti per i quali \u00e8 stato possibile analizzare le cartelle cliniche. Il numero medio di patologie osservate in questa popolazione \u00e8 di 3,7. Complessivamente, 246 pazienti (2,9% del campione) non presentavano patologie, 955 (11,3%) presentavano 1 patologia, 1.512 (17,9%) presentavano 2 patologie e 5.723 (67,8%) presentavano 3 o pi\u00f9 patologie preesistenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Istituto superiore della sanit\u00e0 ha aggiornato il report sui decessi legati alla pandemia in Italia prendendo in esame diverse cartelle cliniche<\/p>\n","protected":false},"author":58,"featured_media":162877,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-162876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=162876"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/162876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162877"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=162876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=162876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=162876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}