{"id":163085,"date":"2022-01-30T18:06:21","date_gmt":"2022-01-30T17:06:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/manca-il-personale-chiuso-il-parco-archeologico-di-sibari\/"},"modified":"2023-01-16T16:58:48","modified_gmt":"2023-01-16T15:58:48","slug":"440774-manca-il-personale-chiuso-il-parco-archeologico-di-sibari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/440774-manca-il-personale-chiuso-il-parco-archeologico-di-sibari\/","title":{"rendered":"Manca il personale, chiuso il Parco Archeologico di Sibari"},"content":{"rendered":"<p>SIBARI (CS) &#8211; E&#8217; chiuso da circa venti giorni il Parco Archeologico di Sibari. Cancelli e porte chiuse a causa della mancanza di personale. A garantire l\u2019apertura erano i tirocinanti, grazie ad un progetto realizzato dalla Regione Calabria e dal Ministero della Cultura, avviato nel 2016. Il contratto, ora, \u00e8 scaduto ed i lavoratori sono costretti a restare a casa.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Chiuso da ormai 20 giorni il Parco Archeologico di Sibari. Scaduto il contratto ai tirocinanti che gestivano la struttura ed i lavoratori sono stati costretti a restare a casa<\/p>\n","protected":false},"author":65,"featured_media":163086,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-163085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/163085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=163085"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/163085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/163086"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=163085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=163085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=163085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}