{"id":163999,"date":"2022-02-13T18:12:52","date_gmt":"2022-02-13T17:12:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/speranza-il-governo-conte-non-ha-assolutamente-pagato-la-scelta-del-lockdown\/"},"modified":"2023-01-16T16:59:47","modified_gmt":"2023-01-16T15:59:47","slug":"443163-speranza-il-governo-conte-non-ha-assolutamente-pagato-la-scelta-del-lockdown","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/443163-speranza-il-governo-conte-non-ha-assolutamente-pagato-la-scelta-del-lockdown\/","title":{"rendered":"Speranza: &#8220;il Governo Conte non ha assolutamente pagato la scelta del lockdown&#8221;"},"content":{"rendered":"<p>ROMA &#8211; &#8220;Il governo Conte non ha assolutamente pagato la scelta del lockdown.<strong> Ha pagato alcune dinamiche pi\u00f9 strettamente politiche ma non certo il lockdown&#8221;<\/strong>, fatto un anno prima che l&#8217;esecutivo cadesse. Lo ha detto il ministro della Salute, <strong>Roberto Speranza<\/strong>.<\/p>\n<p>All&#8217;inizio della pandemia, ha affermato il ministro, &#8220;c&#8217;era una senso di grande unione tra i partiti. Ci sono resoconti parlamentari di quei giorni che raccontano di una grande unit\u00e0 del paese. <strong>Il paese si dimostr\u00f2 migliore di come molti credevano,<\/strong> le divisioni e complessit\u00e0 si sono sviluppate nel secondo anno con l&#8217;arrivo dei vaccini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;C&#8217;era una senso di grande unione tra i partiti. Ci sono resoconti parlamentari di quei giorni che raccontano di una grande unit\u00e0 del paese&#8221;<\/p>\n","protected":false},"author":61,"featured_media":164000,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-163999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/163999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=163999"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/163999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164000"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=163999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=163999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=163999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}