{"id":164169,"date":"2022-02-16T14:24:50","date_gmt":"2022-02-16T13:24:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-consulta-dice-si-ai-4-referendum-sulla-giustizia-attesa-per-quello-sulla-cannabis\/"},"modified":"2023-01-16T16:59:58","modified_gmt":"2023-01-16T15:59:58","slug":"443626-la-consulta-dice-si-ai-4-referendum-sulla-giustizia-attesa-per-quello-sulla-cannabis","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/443626-la-consulta-dice-si-ai-4-referendum-sulla-giustizia-attesa-per-quello-sulla-cannabis\/","title":{"rendered":"La Consulta dice si ai 4 referendum sulla giustizia, attesa per quello sulla cannabis"},"content":{"rendered":"<p>ROMA &#8211;<strong> Via libera della\u00a0Corte costituzionale<\/strong> che dopo aver bocciato ieri quello sull&#8217;eutanasia, ha invece dichiarato l<strong>&#8216;ammissibilit\u00e0 dei 4 Referendum sulla giustizia <\/strong>mentre, nel pomeriggio, arriver\u00e0 <strong>la decisione sul quesito per la liberalizzazione della coltivazione della cannabis.<\/strong> In particolare sono 4 i quesiti ammessi in tema di giustizia e che hanno come obiettivo l<strong>a separazione delle carriere in magistratura<\/strong>, la cancellazione delle firme necessarie per poter presentare una candidatura alle elezioni dei consiglieri togati del Csm, il quesito sulle<strong> limitazioni della custodia cautelare<\/strong> e quello atteso <strong>sulla legge Severino <\/strong>per eliminare la legge sulla incandidabilit\u00e0 e la decadenza di parlamentari e uomini di governo condannati a 2 anni.<\/p>\n<p>La Corte costituzionale ha, infatti, dichiarato l&#8217;ammissibilit\u00e0 del referendum sul<strong> Testo unico delle disposizioni in materia di incandidabilit\u00e0<\/strong>, uno dei decreti attuativi della legge.\u00a0<strong>Sono in tutto 4 per ora i referendum ammessi dalla Corte costituzionale in materia di giustizia<\/strong>, ma l&#8217;esame degli altri quesiti prosegue. Lo sottolinea la stessa Consulta in una nota. Quelli sinora dichiarati ammissibili riguardano l&#8217;abrogazione delle disposizioni in materia di incandidabilit\u00e0, la limitazione delle misure cautelari, la separazione delle funzioni dei magistrati e l&#8217;eliminazione delle liste di presentatori per l&#8217;elezione dei togati del CSM.\u00a0&#8220;I suddetti quesiti &#8211; si spiega nella nota- sono stati ritenuti ammissibili perch\u00e9 le rispettive richieste non rientrano in alcuna delle ipotesi per le quali l&#8217;ordinamento costituzionale esclude il ricorso all&#8217;istituto referendario&#8221;.<\/p>\n<h4>Salvini esulta &#8220;vittoria!&#8221;<\/h4>\n<p>&#8220;Primi quattro referendum sulla giustizia dichiarati ammissibili e presto sottoposti a voto popolare:<strong> vittoria<\/strong>!&#8221; ha scritto\u00a0 su Twitter il leader della Lega, Matteo Salvini.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"it\" dir=\"ltr\">Primi quattro Referendum sulla Giustizia dichiarati ammissibili e presto sottoposti a voto popolare: vittoria! <a href=\"https:\/\/twitter.com\/hashtag\/ReferendumGiustizia?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"noopener\">#ReferendumGiustizia<\/a><\/p>\n<p>&mdash; Matteo Salvini (@matteosalvinimi) <a href=\"https:\/\/twitter.com\/matteosalvinimi\/status\/1493942516995043331?ref_src=twsrc%5Etfw\" rel=\"noopener\">February 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h4>Decaro &#8220;sindaci soddisfatti per il referendum sulla legge Severino&#8221;<\/h4>\n<p>&#8220;Sono contento che il referendum sia passato cos\u00ec anche i <strong>cittadini potranno esprimere la propria opinione.<\/strong> I referendum sono sempre una prova e un esercizio di democrazia da parte dei cittadini. Sulla legge Severino noi sindaci abbiamo chiesto da sempre una modifica perch\u00e9 ci ritroviamo, unica figura istituzionale, ad essere sospesi per 18 mesi senza una condanna definitiva&#8221;. Questo il commento a caldo, con l&#8217;ANSA, sul via libera al quesito referendario sulla legge Severino di Antonio Decaro, presidente dell&#8217;Anci. &#8220;<strong>Non credo che ci sia alcun interesse ad avere un sindaco sospeso per 18 mesi,<\/strong> neanche dalla comunit\u00e0 dei cittadini&#8221;, aggiunge Decaro. &#8220;E mi riferisco anche all&#8217;abuso d&#8217;ufficio, che \u00e8 un reato in cui si pu\u00f2 incorrere facilmente e poi nella stragrande maggioranza dei casi le sentenze sono di assoluzione&#8221;. L<strong>&#8216;elenco dei sindaci sospesi dalla legge Severino e poi riammessi &#8220;\u00e8 lungo<\/strong>&#8220;, sottolinea il presidente Anci. &#8220;Questa battaglia sulla legge Severino noi sindaci l&#8217;abbiamo sempre fatta perch\u00e8, ripeto, vorremmo che ci fosse un trattamento uniforme per tutti e non solo per alcune figure istituzionali&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quattro, per ora, i referendum ammessi in materia di giustizia. Tra questi quello sulla legge Severino e la limitazione delle misure cautelari<\/p>\n","protected":false},"author":55,"featured_media":164170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-164169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=164169"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164170"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=164169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=164169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=164169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}