{"id":164197,"date":"2022-02-16T18:23:28","date_gmt":"2022-02-16T17:23:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/teresa-e-valentina-morte-sulla-106-la-sfogo-della-sorella-ad-occhiuto-non-importano-le-vittime\/"},"modified":"2023-01-16T17:00:00","modified_gmt":"2023-01-16T16:00:00","slug":"443693-teresa-e-valentina-morte-sulla-106-la-sfogo-della-sorella-ad-occhiuto-non-importano-le-vittime","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/443693-teresa-e-valentina-morte-sulla-106-la-sfogo-della-sorella-ad-occhiuto-non-importano-le-vittime\/","title":{"rendered":"Teresa e Valentina morte sulla 106, la sfogo della sorella &#8220;ad Occhiuto non importano le vittime&#8221;"},"content":{"rendered":"<p><b>COSENZA &#8211; <\/b>Il Presidente dell&#8217;Organizzazione di Volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221; Leonardo Caligiuri ha ricevuto oggi, nel 9\u00b0 anniversario di morte di <strong>Teresa e Valentina Fiore, due giovani sorelle che hanno perso la vita sulla Statale 106<\/strong>, una <strong>lettera dalla sorella Antonella<\/strong> che ha inteso condividere con l&#8217;intera comunit\u00e0 calabrese:<\/p>\n<p class=\"v1MsoNormal\">&#8220;Caro Leonardo, nei giorni scorsi ho avuto modo di apprendere che, nel prossimo Consiglio Regionale della Calabria, la Statale 106 sar\u00e0 tra i punti all&#8217;ordine del giorno.\u00a0 Trovo la forza e coraggio di scrivere questa lettera per dire che, secondo il mio personale giudizio, <strong>al presidente Occhiuto, come a tutta la classe dirigente politica calabrese, non importa un fico secco delle persone che sono morte<\/strong> sulla 106, poich\u00e9 per loro sono solo altri numeri. Non sono loro parenti, non sono loro amici e per loro non significano nulla le lacrime che genitori, fratelli, sorelle, nonni, parenti ed amici hanno versato e del dolore che ancora vivono quotidianamente per la loro scomparsa. Perch\u00e9 non vanno a chiedere a mia madre come si sente senza due figlie oppure a mio padre come sta? Il dolore atroce e tremendo che ha lacerato le nostre vite per sempre nessuno di loro lo ha provato. Giudici, avvocati, Regione e Stato, nessuno si \u00e8 messo nei panni di mia mamma o di mio padre o di noi sorelle! Ti chiedo: dalle mie parole si comprende il mio ed il nostro dolore?<\/p>\n<p class=\"v1MsoNormal\">Vorrei tanto far vedere loro mia figlia di tre anni come saluta le zie dal cielo oppure come le bacia dalle foto che abbiamo a casa. Quando avrebbe potuto stringerle forte e giocare con loro! Il dolore che proviamo noi vorrei che loro riuscissero a capirlo. Io soffro solo a guardare le loro foto e questa lettera la sto scrivendo tra le lacrime ma non sai cosa darei per far sentire ai vertici politici della Calabria la mia sofferenza e quella della mia famiglia.<\/p>\n<p class=\"v1MsoNormal\">Oggi ricorre il <strong>9\u00b0 anniversario della morte delle mie sorelle Teresa di 25 anni e Valentina di 21 anni<\/strong> e da allora sulla Statale 106 le cose sono peggiorate ed altre persone hanno perso la vita. Questa \u00e8 una sconfitta per la Calabria, ma ancora di pi\u00f9 per l&#8217;Italia che ha perso giovani che in un futuro avrebbero potuto dare al Paese un contributo importante! Le mie sorelle hanno trovato una morte prematura nel fiore della loro et\u00e0. Avevano un lavoro e tanti hobby che coltivavano, oltre ad avere molti amici. Purtroppo il 16 febbraio del 2013 sono state uccise su quella maledetta strada e giustizia non abbiamo avuto ma ci\u00f2 che \u00e8 peggio \u00e8 che da nove anni sulla Statale 106 <strong>continuano a morire ancora molte persone<\/strong>, tra cui tanti giovani.<\/p>\n<p class=\"v1MsoNormal\">Vorrei tanto che la classe politica dirigente regionale riuscisse a capire quanto \u00e8 importante eseguire i lavori sulla 106. Perch\u00e9 si possono salvare tante vite, evitare a tante mamme e tanti pap\u00e0 di versare lacrime all&#8217;infinito. Il dolore che si prova \u00e8 immenso. Le domande che ci poniamo sono tante e una riecheggia nella nostra mente: verr\u00e0 mai la fine della sofferenza per noi familiari delle vittime della 106? Rifare la strada non ci ridar\u00e0 i nostri cari ma servir\u00e0 ad altre famiglie a non vivere mai pi\u00f9 quello che purtroppo stiamo vivendo noi.<\/p>\n<p class=\"v1MsoNormal\">Sono convinta che nessuno di quelle persone terr\u00e0 in considerazione ci\u00f2 che scrivo, perch\u00e9 purtroppo \u00e8 cos\u00ec.<strong> A costoro per\u00f2 vorrei fare delle domande<\/strong>: avete pensato che magari sistemando la 106 tanti genitori potrebbero dormire pi\u00f9 tranquilli? Avete pensato che se siete l\u00ec e perch\u00e9 avete fatto promesse che non avete mai mantenuto? Vi chiedo: ma non vi vergognate guardandovi allo specchio nel vedere tutti noi familiari soffrire? Tutto questo non vi basta? Avete percorso almeno una volta la 106? Sono anni che parlano di mettere in sicurezza e di ammodernare la strada ma nessuno fa mai niente. Vorrei tanto portare i nostri politici a vedere dove si trovano ora le mie sorelle per farli rendere conto di ci\u00f2 che hanno fatto. Si, hanno fatto! Perch\u00e9 la colpa \u00e8 la loro e di tutti gli altri che negli anni si sono succeduti&#8230;Fate qualcosa. Fatela in fretta. Se ne siete capaci&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 9\u00b0 anniversario dalla morte di due giovani sorelle, di 25 e 21 anni, sul tratto stradale, la lettera della sorella Antonella rivolta ai vertici della politica calabrese<\/p>\n","protected":false},"author":58,"featured_media":164198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-164197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=164197"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164198"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=164197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=164197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=164197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}