{"id":164321,"date":"2022-02-18T16:16:22","date_gmt":"2022-02-18T15:16:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/giovani-e-periferie-da-cassano-percorsi-formativi-per-una-possibilita-di-riscatto\/"},"modified":"2023-01-16T17:00:08","modified_gmt":"2023-01-16T16:00:08","slug":"444054-giovani-e-periferie-da-cassano-percorsi-formativi-per-una-possibilita-di-riscatto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/444054-giovani-e-periferie-da-cassano-percorsi-formativi-per-una-possibilita-di-riscatto\/","title":{"rendered":"Giovani e periferie, da Cassano percorsi formativi per una possibilit\u00e0 di riscatto"},"content":{"rendered":"<p>CASSANO IONIO (CS) &#8211; Realizzare <strong>progetti e percorsi formativi per i giovani, soprattutto quelli delle periferie.<\/strong> Questo l&#8217;obiettivo di un incontro, che si \u00e8 svolto a Cassano Ionio, che ha visto la Diocesi, la Regione Calabria, la Fondazione con il Sud e l&#8217;impresa sociale Kairos confrontarsi per offrire una possibilit\u00e0 di riscatto. Portare esperienze positive di persone che ce l&#8217;hanno fatta, hanno ribadito Carlo Borgomeo, Presidente Fondazione con il Sud e Mons. Francesco Savino, Vescovo della Diocesi di Cassano Ionio, pu\u00f2 suscitare percorsi emulativi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo l&#8217;obiettivo di un incontro che ha visto la Diocesi, la Regione Calabria, la Fondazione con il Sud e l&#8217;impresa sociale Kairos confrontarsi<\/p>\n","protected":false},"author":65,"featured_media":164322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[135],"class_list":["post-164321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=164321"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164322"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=164321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=164321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=164321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}