{"id":164337,"date":"2022-02-20T09:00:08","date_gmt":"2022-02-20T08:00:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/contrasto-alla-poverta-il-comune-di-cariati-cerca-uno-psicologo\/"},"modified":"2023-01-16T17:00:09","modified_gmt":"2023-01-16T16:00:09","slug":"444096-contrasto-alla-poverta-il-comune-di-cariati-cerca-uno-psicologo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/444096-contrasto-alla-poverta-il-comune-di-cariati-cerca-uno-psicologo\/","title":{"rendered":"Contrasto alla povert\u00e0, Il Comune di Cariati cerca uno psicologo"},"content":{"rendered":"<p class=\"v1MsoNormal\">CARIATI (CS) &#8211; Inclusione e contrasto alla povert\u00e0, si cerca <strong>uno psicologo esterno<\/strong> <strong>da inserire nella short list di professionisti <\/strong>in forze al programma rivolto ai cittadini dell&#8217;Ambito Sociale Territoriale N.2 (Cariati, Bocchigliero, Campana, Scala Coeli, Terravecchia, Mandatoriccio e Pietrapaola). Sono stati prorogati i termini per la manifestazione di interesse. Scadono <strong>luned\u00ec 28.<\/strong><\/p>\n<p class=\"v1MsoNormal\">Pu\u00f2 candidarsi chi \u00e8 in possesso di diploma di laurea magistrale o specialistica in psicologia; iscritto all&#8217;Ordine degli Psicologi; in possesso di un&#8217;esperienza lavorativa in qualit\u00e0 di psicologo; con patente categoria B ed automunito\/a. La domanda di ammissione dovr\u00e0 essere redatta sull&#8217;apposito modello,<strong> indirizzata al Comune di Cariati<\/strong> &#8211; Capofila Ambito Territoriale n. 2 ASP Cosenza e dovr\u00e0 essere inviata esclusivamente a mezzo PEC all&#8217;indirizzo\u00a0<a href=\"mailto:protocollo.cariati@asmepec.it\" rel=\"noreferrer\">protocollo.cariati@asmepec.it<\/a>.<\/p>\n<p class=\"v1MsoNormal\">Nella domanda i\/le candidati\/e dovranno chiedere espressamente di voler partecipare alla <strong>Selezione pubblica, per titolo e colloquio<\/strong>, per il profilo specifico e dovranno dichiarare, sotto la loro personale responsabilit\u00e0, tra le altre informazioni, la residenza, il codice fiscale, il recapito (con l&#8217;indicazione del numero telefonico) presso il quale deve essere fatta qualsiasi comunicazione relativa alla selezione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono stati prorogati i termini per la manifestazione di interesse che scadono luned\u00ec 28 febbraio. La selezione pubblica avverr\u00e0 per titolo e colloquio<\/p>\n","protected":false},"author":58,"featured_media":164338,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-164337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=164337"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164338"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=164337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=164337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=164337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}