{"id":164427,"date":"2022-02-21T11:02:53","date_gmt":"2022-02-21T10:02:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-covid-ha-inciso-su-i-matrimoni-474-rispetto-al-2019\/"},"modified":"2023-01-16T17:00:15","modified_gmt":"2023-01-16T16:00:15","slug":"444349-il-covid-ha-inciso-su-i-matrimoni-474-rispetto-al-2019","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/444349-il-covid-ha-inciso-su-i-matrimoni-474-rispetto-al-2019\/","title":{"rendered":"Il Covid ha inciso su i matrimoni: -47,4% rispetto al 2019"},"content":{"rendered":"<p>ROMA &#8211; Nel 2020 la pandemia ha indotto molte persone a rinviare o rinunciare alle nozze. I matrimoni celebrati in Italia<strong> sono stati 96.841, il 47,4% in meno rispetto al 2019.<\/strong> In calo soprattutto le nozze con rito religioso (-67,9%) e i primi matrimoni (-52,3%). Per i primi nove mesi del 2021 i dati provvisori indicano, rispetto allo stesso periodo del 2020, <strong>un raddoppio dei matrimoni, ma la ripresa non \u00e8 sufficiente<\/strong> a recuperare quanto perso nell&#8217;anno precedente. Diminuiscono <strong>anche le unioni civili tra partner dello stesso sesso<\/strong> (-33,0%), le separazioni (-18,0%) e i divorzi (-21,9%). E&#8217; quanto emerge dal report Istat 2020.<\/p>\n<p>I dati Istat del 2020 dunque danno conto dell&#8217;impatto della pandemia da Covid-19 sui matrimoni, <strong>evidenziando un crollo di portata eccezionale che ha quasi dimezzato il numero delle nozze<\/strong> in un solo anno: sono stati celebrati 96.841 matrimoni, 87 mila in meno rispetto al 2019 (-47,4%). La battuta d&#8217;arresto si osserva a partire da marzo 2020 con picchi ad aprile e maggio proprio per via delle pesanti restrizioni imposte dalla pandemia. <strong>Alcune misure di contenimento<\/strong> (divieto di assembramenti, numero massimo di persone in caso di eventi) hanno comunque riguardato l&#8217;intero anno 2020 e si sono protratte nel 2021. <strong>Ulteriori elementi a sfavore delle nozze si sono aggiunti,<\/strong> via via, a seguito del dispiegarsi degli effetti sociali ed economici indotti dalla crisi sanitaria. A livello territoriale, il calo \u00e8 molto pi\u00f9 pronunciato nel Mezzogiorno (-54,9%) rispetto al Centro (-46,1%) e, soprattutto, al Nord (-40,6%).<\/p>\n<p>L&#8217; incremento dipende prevalentemente dalla crescita delle libere unioni di celibi e nubili (da 170mila a 863mila circa). <strong>Negli ultimi due decenni, inoltre, il netto ridimensionamento delle nuove generazioni,<\/strong> dovuto alla fecondit\u00e0 bassa e tardiva osservata a partire dalla met\u00e0 degli anni Settanta, ha prodotto un effetto strutturale negativo sui matrimoni cos\u00ec come sulle nascite. Man mano che queste generazioni, molto meno <strong>numerose di quelle dei loro genitori, entrano nella fase della vita adulta si riduce infatti la numerosit\u00e0<\/strong> della popolazione in et\u00e0 da matrimonio e, di conseguenza, a parit\u00e0 di propensione a sposarsi, cala il numero assoluto di nozze. La diminuzione tendenziale di lungo periodo ha avuto alcune oscillazioni congiunturali.<\/p>\n<p>Per esempio, un aumento dei matrimoni \u00e8 stato osservato nel 2000, per l&#8217;attivit\u00e0 che tale anno ha esercitato su chi ha voluto celebrare le proprie nozze all&#8217;inizio del nuovo millennio.<strong> All&#8217;opposto, nel triennio 2009-2011 la diminuzione \u00e8 stata particolarmente accentuata e dovuta al crollo delle nozze dei cittadini stranieri<\/strong>, scoraggiati dalle modifiche legislative volte a limitare i matrimoni di comodo e dagli effetti della crisi del 2008 che li ha colpiti particolarmente. La caduta dei matrimoni<strong> \u00e8 attribuibile soprattutto al calo delle prime nozze che, nel 2020, registrano un nuovo minimo, soltanto 69.743 (-52,3% rispetto al 2019)<\/strong>. A diminuire di pi\u00f9 sono state le prime nozze con lo sposo in et\u00e0 tra 30 e 39 anni (-55,8%) e quelle con la sposa fino a 39 anni (-54,4%). Un calo pi\u00f9 limitato riguarda invece i primi matrimoni<strong> in cui entrambi gli sposi hanno almeno 50 anni (-26,9%)<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 2020 al 2022 sono nettamente diminuite anche le unioni civili tra partner dello stesso sesso, le separazioni e i divorzi<\/p>\n","protected":false},"author":61,"featured_media":164428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-164427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=164427"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/164427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/164428"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=164427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=164427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=164427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}