{"id":16448,"date":"2013-01-24T12:15:43","date_gmt":"2013-01-24T11:15:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16448"},"modified":"2023-01-17T13:14:32","modified_gmt":"2023-01-17T12:14:32","slug":"5659-ndrangheta-organizzazione-diversa-dalle-altre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5659-ndrangheta-organizzazione-diversa-dalle-altre\/","title":{"rendered":"&#8216;Ndrangheta, organizzazione diversa dalle altre"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 1;\"><strong>REGGIO CALABRIA<\/strong> &#8211; Una moltitudine di &#8220;cloni&#8221; nelle piu&#8217; importanti e ricche regioni italiane e in numerosi Paesi posti in diversi e lontani continenti.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\"> E&#8217; il modello che, secondo l&#8217;ultima relazione annuale della Dna, fa della &#8216;ndrangheta un&#8217;organizzazione di tipo mafioso diversa da tutte le altre presenti in Italia, capace di rendere &#8220;stabile e strutturata&#8221; la propria influenza al di fuori della Calabria. Due le tendenze isolate dagli analisti: la &#8220;colonizzazione&#8221; di intere aree e la presenza &#8220;sommersa&#8221; in altre.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\">Nel primo caso, come in Lombardia e in Piemonte, si registra &#8220;l&#8217;espansione di alcune &#8216;ndrine su di un nuovo territorio nel quale &#8211; sul modello della &#8216;casa madre&#8217; &#8211; viene organizzato ed esercitato un controllo stringente ed opprimente (con attentati, intimidazioni, richieste estorsive, accaparramento di appalti e sub-appalti, contiguita&#8217; con il mondo politico ed amministrativo). Nel secondo, si verifica &#8220;la presenza di un nucleo, anche consistente, di esponenti della &#8216;ndrangheta che operano in favore della &#8216;ndrina di riferimento ma che, tuttavia, non solo non si costituiscono formalmente in &#8216;locale&#8217;, ma che non svolgono neanche le tipiche attivita&#8217; delittuose dell&#8217;organizzazione di appartenenza, limitandosi a gestire, in modo discreto, gli &#8216;affari&#8217; per conto dell&#8217;organizzazione&#8221;, dal riciclaggio al reimpiego dei capitali sporchi passando per i rapporti finalizzati a coordinare i vari traffici di droga.<\/span><span style=\"font-size: 12px; line-height: 1;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Una moltitudine di &#8220;cloni&#8221; nelle piu&#8217; importanti e ricche regioni italiane e in numerosi Paesi posti in diversi e lontani continenti.<\/p>\n","protected":false},"author":22,"featured_media":16449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-16448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16448"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16449"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}