{"id":165021,"date":"2022-03-02T15:10:01","date_gmt":"2022-03-02T14:10:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/concorso-allievi-marescialli-carabinieri-2022-671-posti-da-ispettore-per-diplomati\/"},"modified":"2023-01-16T17:00:54","modified_gmt":"2023-01-16T16:00:54","slug":"445852-concorso-allievi-marescialli-carabinieri-2022-671-posti-da-ispettore-per-diplomati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/445852-concorso-allievi-marescialli-carabinieri-2022-671-posti-da-ispettore-per-diplomati\/","title":{"rendered":"Concorso allievi Marescialli Carabinieri 2022 &#8211; 671 posti da ispettore per diplomati"},"content":{"rendered":"<p>COSENZA &#8211;\u00a0Il Ministero della Difesa ha indetto un nuovo concorso per l&#8217;arma dei Carabinieri 2022 che prevede il <strong>reclutamento di <\/strong><strong>671 Allievi Marescialli <\/strong>del <strong>ruolo Ispettori dell\u2019Arma<\/strong> al 12\u00b0 corso triennale 2022-2025. Il bando prevede l\u2019espletamento di varie prove scritte ed orali, di accertamenti psico-fisici e di una iniziale prova preliminare. <strong>I<\/strong><strong>l<a href=\"https:\/\/quicosenza.it\/news\/14682\" target=\"_blank\" rel=\"noopener\"> bando<\/a> per il concorso Allievi Marescialli Carabinieri 2022 mette a disposizione 671 posti, di cui 134 sono riservati:<\/strong><\/p>\n<p>\u2013 al coniuge e ai figli superstiti, ovvero ai parenti in linea collaterale di secondo grado se unici superstiti, del personale delle Forze Armate, compresa l\u2019Arma dei Carabinieri, e delle Forze di Polizia deceduto in servizio e per causa di servizio<\/p>\n<p>\u2013 ai diplomati delle Scuole militari dell\u2019Esercito, della Marina e dell\u2019Aeronautica<\/p>\n<p>\u2013 agli assistiti dall\u2019Opera nazionale di assistenza per gli orfani dei militari di carriera dell\u2019Esercito italiano, dall\u2019Istituto Andrea Doria per l\u2019assistenza dei familiari e degli orfani del personale della Marina Militare, dall\u2019Opera nazionale per i figli degli aviatori e dall\u2019Opera nazionale di assistenza per gli orfani dei militari dell\u2019Arma dei Carabinieri, in possesso dei prescritti requisiti<\/p>\n<p>I posti riservati eventualmente non ricoperti per insufficienza di candidati riservatari idonei saranno devoluti agli altri candidati idonei secondo l\u2019ordine della graduatoria di merito. \u00c8 stabilito in <strong>28 il numero dei vincitori del concorso da formare nelle specializzazioni in materia di sicurezza e tutela ambientale, forestale e agroalimentare<\/strong>. All\u2019atto della presentazione della domanda, i candidati hanno facolt\u00e0 di esprimere preferenza per la formazione e per l\u2019impiego nelle specializzazioni.<\/p>\n<p><strong>REQUISITI\u00a0<\/strong><\/p>\n<p>Possono partecipare al Concorso 671 Allievi Marescialli Carabinieri\u00a0 le persone con i seguenti requisiti:<\/p>\n<ol>\n<li><strong>A) <\/strong><strong>I militari dell\u2019Arma dei Carabinieri appartenenti al ruolo dei Sovrintendenti ed a quello degli Appuntati e Carabinieri, e Allievi Carabinieri, in possesso dei seguenti requisiti:<\/strong><\/li>\n<\/ol>\n<p>\u2013 idoneit\u00e0 al servizio militare incondizionato o temporanea inidoneit\u00e0 (nel secondo caso \u00e8 prevista l\u2019ammissione con riserva)<br \/>\n\u2013 aver conseguito un diploma (o essere in grado di conseguirlo entro il termine dell\u2019anno scolastico 2021-2022) di istruzione secondaria di secondo grado, di durata quinquennale o quadriennale con anno integrativo<br \/>\n\u2013 et\u00e0 non superiore a 30 anni (precisamente non aver superato il giorno del compimento del 30\u00b0 anno di et\u00e0);<br \/>\n\u2013 non aver riportato negli ultimi due anni o nel periodo di servizio, se inferiore a due anni, sanzioni disciplinari pi\u00f9 gravi della consegna, una qualifica inferiore a \u201cnella media\u201d o giudizi corrispondenti, o giudizi di inidoneit\u00e0 all\u2019avanzamento di grado<br \/>\n\u2013 non siano stati condannati per delitti non colposi, anche con sentenza di applicazione della pena su richiesta o con decreto penale di condanna, a pena condizionalmente sospesa o con il beneficio della non menzione<br \/>\n\u2013 non siano in atto imputati in procedimenti penali per delitti non colposi<br \/>\n\u2013 non siano sottoposti a procedimento disciplinare di stato o sospesi dall\u2019impiego o in aspettativa per qualsiasi motivo per una durata non inferiore a 60 giorni<br \/>\n\u2013 nel caso di procedimento penale per delitti non colposi precedentemente instaurato nei loro confronti e non concluso con sentenza irrevocabile di assoluzione (perch\u00e9 il fatto non sussiste ovvero perch\u00e9 l\u2019imputato non lo ha commesso, pronunciata ai sensi dell\u2019articolo 530 del codice di procedura penale).<\/p>\n<p><strong>B) <\/strong><strong>I cittadini italiani in possesso dei seguenti requisiti:<\/strong><\/p>\n<p>\u2013 et\u00e0 non inferiore a 17 anni compiuti e non superiore a 26 anni (ovvero al giorno del compimento degli stessi) o, per coloro che hanno gi\u00e0 prestato servizio militare per un periodo non inferiore alla ferma obbligatoria, a 28 anni<br \/>\n\u2013 se minorenni, possesso del consenso dei genitori o di chi esercita la potest\u00e0 genitoriale<br \/>\n\u2013 godimento dei diritti civili e politici<br \/>\n\u2013 assenza di condanne e procedimenti penali in corso per delitti non colposi, o di situazioni incompatibili con l\u2019acquisizione e la conservazione dello stato di Maresciallo dei Carabinieri<br \/>\n\u2013 avere condotta incensurabile e non aver tenuto comportamenti nei confronti delle istituzioni democratiche che non diano sicuro affidamento di scrupolosa fedelt\u00e0 alla Costituzione repubblicana e alle ragioni di sicurezza dello Stato<br \/>\n\u2013 abbiano conseguito o siano in grado di conseguire, al termine dell\u2019anno scolastico 2021-2022, il diploma di istruzione secondaria di secondo grado di durata quinquennale ovvero quadriennale integrato dal corso annuale previsto per l\u2019accesso all\u2019universit\u00e0<br \/>\n\u2013 non essere stati destituiti, dispensati o dichiarati decaduti dall\u2019impiego in una pubblica amministrazione, licenziati da un impiego pubblico per procedimento disciplinare o prosciolti, d\u2019autorit\u00e0 o d\u2019ufficio, da precedente arruolamento nelle Forze Armate o di Polizia, eccetto che per non idoneit\u00e0 psico-fisica<br \/>\n\u2013 non essere stati sottoposti a misure di prevenzione<br \/>\n\u2013 se militari nel caso di procedimento penale per delitti non colposi, precedentemente instaurato nei loro confronti e non concluso con sentenza irrevocabile di assoluzione (perch\u00e9 il fatto non sussiste ovvero perch\u00e9 l\u2019imputato non lo ha commesso, pronunciata ai sensi dell\u2019articolo 530 del codice di procedura penale), non siano sottoposti a conseguente procedimento disciplinare in corso di definizione.<\/p>\n<p><strong>DOMANDA AL CONCORSO<\/strong><\/p>\n<p>La domanda di partecipazione al Concorso dovr\u00e0 pervenire entro e non oltre il 24 Marzo 2022. La domanda dovr\u00e0 essere compilata esclusivamente online attraverso l\u2019apposita procedura online, raggiungibile dalla sezione Carabinieri Concorsi del portale web <a href=\"https:\/\/quicosenza.it\/news\/14683\">https:\/\/extranet.carabinieri.it\/ConcorsiOnline20<\/a> . Per poter presentare la domanda di ammissione al concorso, \u00e8 necessario che i candidati siano in possesso di uno dei seguenti strumenti identificativi:<br \/>\n&#8211; SPID (con livello di sicurezza 2);<br \/>\n&#8211; Lettore di smart-card installato nel computer per l\u2019utilizzo con carta nazionale dei servizi (CNS).<\/p>\n<p><strong>PROVE DEL CONCORSO<\/strong><\/p>\n<p>Il Concorso 671 Allievi Marescialli Carabinieri prevede le seguenti prove:<\/p>\n<ol>\n<li>a) Prova preliminare<br \/>\nb) Prove di Efficienza Fisica<br \/>\nc) Prova scritta di Conoscenza della Lingua Italiana<br \/>\nd) Accertamenti Psico-fisici per la verifica dell\u2019idoneit\u00e0 psico\u2013fisica<br \/>\ne) Accertamenti Attitudinali<br \/>\nf) Prova Orale<\/li>\n<\/ol>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/14684\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">CLICCA QUI PER SCRICARE IL BANDO DI CONCORSO<\/span><\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Arma dei Carabinieri ha indetto un nuovo concorso aperto ai civili in possesso del solo diploma per 671 Allievi Marescialli<\/p>\n","protected":false},"author":55,"featured_media":165022,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-165021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165021"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165022"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}