{"id":165048,"date":"2022-03-05T17:00:30","date_gmt":"2022-03-05T16:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-guerra-e-i-bambini-come-parlarne-ai-piu-piccoli\/"},"modified":"2023-01-16T17:00:56","modified_gmt":"2023-01-16T16:00:56","slug":"445937-la-guerra-e-i-bambini-come-parlarne-ai-piu-piccoli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/445937-la-guerra-e-i-bambini-come-parlarne-ai-piu-piccoli\/","title":{"rendered":"La guerra e i bambini: come parlarne ai pi\u00f9 piccoli"},"content":{"rendered":"<div dir=\"ltr\">\n<div class=\"gmail_default\">\n<div class=\"gmail-row\">\n<div class=\"gmail-col-md-12\">\n<p>RENDE &#8211; \u00c8 opportuno parlare ai bambini della guerra in atto in Ucraina? E come farlo in maniera opportuna in ambito scolastico e a casa? <strong>Francesco Craig, ricercatore di Psicologia clinica<\/strong> del dipartimento di Culture, educazione e societ\u00e0 dell&#8217;Universit\u00e0 della Calabria ci spiega come affrontare la situazione con i bambini pi\u00f9 piccoli.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Francesco Craig, ricercatore di Psicologia clinica del dipartimento di Culture, educazione e societ\u00e0 dell&#8217;Unical spiega come affrontare la situazione con i pi\u00f9 piccoli<\/p>\n","protected":false},"author":42,"featured_media":165049,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-165048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165048"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165049"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}