{"id":16540,"date":"2013-01-25T13:49:16","date_gmt":"2013-01-25T12:49:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16540"},"modified":"2023-01-17T13:14:36","modified_gmt":"2023-01-17T12:14:36","slug":"5710-in-agitazione-dipendenti-clinica-madonna-della-catena","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5710-in-agitazione-dipendenti-clinica-madonna-della-catena\/","title":{"rendered":"In agitazione dipendenti clinica Madonna della Catena"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211; Di nuovo agitazione per i dipendenti&nbsp;della clinica Madonna della Catena di Laurignano, frazione di Dipignano (Cosenza).<\/p>\n<p>  <!--more-->  <\/p>\n<p>I lavoratori non credono che il nuovo piano di rilancio della struttura sia adeguato al mentenimento della pianta organica attuale, di 160 dipendenti, e temono licenziamenti. Inoltre i dipendenti vantano un credito di 11 stipendi arretrati. Attualmente la struttura e&#8217; retta da un commissario liquidatore, anche se c&#8217;e&#8217; un imprenditore che vorrebbe rilevarla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Di nuovo agitazione per i dipendenti&nbsp;della clinica Madonna della Catena di Laurignano, frazione di Dipignano (Cosenza).<\/p>\n","protected":false},"author":22,"featured_media":16541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-16540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16540"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16541"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}