{"id":165482,"date":"2022-03-10T10:39:44","date_gmt":"2022-03-10T09:39:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/emergenza-rifiuti-melicchio-a-manna-gioca-allo-scaricabarile\/"},"modified":"2023-01-16T17:01:25","modified_gmt":"2023-01-16T16:01:25","slug":"447087-emergenza-rifiuti-melicchio-a-manna-gioca-allo-scaricabarile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/447087-emergenza-rifiuti-melicchio-a-manna-gioca-allo-scaricabarile\/","title":{"rendered":"Emergenza rifiuti, Melicchio a Manna: &#8220;gioca allo scaricabarile&#8221;"},"content":{"rendered":"<p>RENDE (CS) &#8211; &#8220;A che serve l&#8217;Ato 1 Rifiuti se la sua massima decisione consiste nel decretare di non essere in grado di prendere una decisione? E per questo motivo demanda ad altri i compiti istituzionali che dovrebbe portare avanti. A quanto pare questa \u00e8 la logica contorta che governa la gestione dei rifiuti in Calabria e ci tiene bloccati nell&#8217;emergenza&#8221;. A dirlo in un comunicato \u00e8 l&#8217;<strong>onorevole Alessandro Melicchio.<\/strong><\/p>\n<p>&#8220;Mancava la guerra in Ucraina a complicare la situazione e a far emergere tutta la fragilit\u00e0 del sistema. Ieri il presidente dell&#8217;Ato, Marcello Manna, ha spiegato che <strong>parte dei rifiuti raccolti vengono spediti in Svezia<\/strong>, ma il conflitto ha bloccato le navi facendo piombare<strong> la provincia di Cosenza nel caos gestionale.<\/strong> E ha continuato ad invocare l&#8217;intervento della Regione\u00a0 &#8211; dice Melicchio &#8211; per la nomina di un commissario che possa assumersi la responsabilit\u00e0 di prendere quella fatidica decisione che l&#8217;assemblea dei sindaci, <strong>capitanata dallo stesso Manna, non \u00e8 in grado di assumere:<\/strong> l&#8217;individuazione di un sito dove poter realizzare l&#8217;ecodistretto. A questo punto ci chiediamo: ma in tutti questi anni (dal 2018 ad oggi) a cosa \u00e8 servito questo organismo diretto da Manna? E qual \u00e8 stato il valore aggiunto del presidente se non riesce a sbrogliare la matassa e continua a chiedere che qualcun altro agisca al suo posto? Per <strong>il bene della Calabria e della provincia di Cosenza<\/strong> &#8211; conclude Melicchio &#8211;\u00a0 \u00e8 sicuramente il caso di azzerare tutto e ripartire daccapo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ma in tutti questi anni, dal 2018 ad oggi, a cosa \u00e8 servito questo organismo diretto da Manna? E&#8217; sicuramente il caso di azzerare tutto e ripartire daccapo&#8221;<\/p>\n","protected":false},"author":61,"featured_media":165483,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-165482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165482"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165483"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}