{"id":165616,"date":"2022-03-12T09:40:04","date_gmt":"2022-03-12T08:40:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/anziana-rinchiusa-in-una-stanza-e-derubata-della-pensione-arrestate-figlia-e-nipote\/"},"modified":"2023-01-16T17:01:34","modified_gmt":"2023-01-16T16:01:34","slug":"447390-anziana-rinchiusa-in-una-stanza-e-derubata-della-pensione-arrestate-figlia-e-nipote","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/447390-anziana-rinchiusa-in-una-stanza-e-derubata-della-pensione-arrestate-figlia-e-nipote\/","title":{"rendered":"Anziana rinchiusa in una stanza e derubata della pensione: arrestate figlia e nipote"},"content":{"rendered":"<p>CATANZARO \u2013 La polizia ha oggi posto fine ad <strong>una storia di violenze fisiche e verbali ai danni di un\u2019anziana signora a Catanzaro Lido<\/strong>. Il commissariato ha, quindi, eseguito una misura cautelare di allontanamento dalla casa familiare e di divieto di avvicinamento ai luoghi abitualmente<strong> frequentati dalla persona offesa, emessa dal Gip presso il Tribunale di Catanzaro,<\/strong> su richiesta della locale Procura della Repubblica, per il reato di maltrattamenti in famiglia a carico di due soggetti.<\/p>\n<p>L\u2019ipotesi <strong>\u00e8 che due donne, rispettivamente figlia e nipote di un\u2019anziana donna,<\/strong> abbiano sottoposto sistematicamente<strong> la persona offesa ad atti di violenza fisica e verbale;<\/strong> si siano impossessate della sua carta bancomat e quindi dei suoi risparmi, della sua pensione (<strong>ammontante a 1.000,00 euro<\/strong>) e di quella di reversibilit\u00e0 del coniuge; le abbiano negato l\u2019acquisto di generi alimentari, di vestiti e di ricorrere a visite o cure mediche; <strong>l\u2019abbiano costretta a vivere nella sua stanza, privandola della possibilit\u00e0 di intrattenere relazioni col mondo esterno<\/strong>, di avere la disponibilit\u00e0 di un televisore e di un telefono; in qualche occasione, l\u2019abbiano finanche lasciata nel cortile di casa in condizioni meteorologiche avverse.\u00a0\u00a0Il procedimento pende nella fase delle indagini preliminari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ipotesi \u00e8 che due donne rispettivamente figlia e nipote di un\u2019anziana donna abbiano sottoposto sistematicamente la persona offesa ad atti di violenza fisica e verbale<\/p>\n","protected":false},"author":61,"featured_media":165617,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-165616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165616"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165617"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}