{"id":165759,"date":"2022-03-14T19:02:58","date_gmt":"2022-03-14T18:02:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-covid-corre-di-piu-al-centrosud-pregliasco-omicron-2-e-3-sono-contagiosissime\/"},"modified":"2023-01-16T17:01:42","modified_gmt":"2023-01-16T16:01:42","slug":"447744-il-covid-corre-di-piu-al-centrosud-pregliasco-omicron-2-e-3-sono-contagiosissime","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/447744-il-covid-corre-di-piu-al-centrosud-pregliasco-omicron-2-e-3-sono-contagiosissime\/","title":{"rendered":"Il covid corre di pi\u00f9 al centrosud. Pregliasco &#8220;Omicron 2 e 3 sono contagiosissime&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Il covid ha ricominciato a correre (in realt\u00e0 nella nostra regione sembra non aver praticamente mai veramente rallentato in maniera decisa) e conferma <strong>una circolazione elevata<\/strong> nel nostro come in altri Pesi europei. Ed un impatto maggiore si vede, al momento, <strong>soprattutto nelle regioni italiane del Centrosud<\/strong>, con casi come quello della Toscana dove il tasso di positivit\u00e0 raggiunge il 17% o quello della Sicilia dove si segnalano primi focolai in alcuni ospedali. A dimostrazione, ha avvertito <strong>il ministro della Salute Roberto Speranza,<\/strong> che &#8220;la pandemia non \u00e8 scomparsa e il virus continua a circolare. E&#8217; una fase diversa, ma serve mantenere cautela&#8221;. In questa fase, ha ricordato infatti il ministro, la protezione che ci danno i vaccini &#8220;\u00e8 altissima ma non dobbiamo pensare che il virus non c&#8217;\u00e8 pi\u00f9&#8221;, <strong>mentre le mascherine al chiuso &#8220;continuano a essere un elemento molto importante<\/strong>&#8220;.<\/p>\n<h4>Pregliasco &#8220;Riapriamo ma con il buonsenso&#8221;<\/h4>\n<p>Un richiamo alla prudenza legato appunto ai numeri in risalita legati alla maggiore contagiosit\u00e0 della sub varianti di Omicron come ha sottolineato<strong> il virologo Fabrizio Pregliasco che<\/strong> invita a mantenere le misure anche dopo la fine dello stato di emergenza a fronte della maggiore contagiosit\u00e0 &#8220;<strong>le nuove varianti Omicron, la 2 e la 3, sono contagiosissime<\/strong>,<strong> molto pi\u00f9 della prima<\/strong>. Da fine mese non si devono aprire i rubinetti istantaneamente, sarebbe meglio che l&#8217;utilizzo del Green Pass ed altre restrizioni rimanessero ancora e venissero tolte progressivamente dal 31 marzo&#8221; ha detto in un intervista a Rai Radio1. &#8220;Riapriamo con buonsenso perch\u00e9 vedremo tra una quindicina di giorni gli effetti di questo rialzo. Se i dati delle terapie intensive e la mortalit\u00e0 dovessero risalire &#8211; ha spiegato Pregliasco &#8211; allora andranno fatti ragionamenti diversi sul mantenere pi\u00f9 cautela&#8221;.<\/p>\n<h4>Gimbe &#8220;tasso di positivit\u00e0 alto in <strong>Umbria, Toscana e\u00a0 Calabria&#8221;<\/strong><\/h4>\n<p>Il dato generale di quest&#8217;ultima fase in Italia, ha quindi evidenziato il presidente della Fondazione Gimbe Nino Cartabellotta, \u00e8 che &#8220;siamo di fronte a una circolazione molto elevata del virus: i casi attualmente positivi sono risaliti sopra il milione, il<strong> tasso di positivit\u00e0 si attesta al 12-12,5% e questo tipo di aumento interessa un po&#8217; tutte le Regioni e in particolare alcune del Sud e Centro Italia come l&#8217;Umbria, la Toscana, la Calabria<\/strong>. Inoltre i dati provenienti dall&#8217;Europa ci dicono che il virus sta rialzando la testa un po&#8217; in tutti i Paesi&#8221;.<\/p>\n<h4>La situazione ospedaliera resta sotto controllo<\/h4>\n<p>Che la ripresa dei contagi stia avvenendo in tutta Europa lo dimostrano pure le analisi del matematico del Cnr Giovanni Sebastiani, secondo il quale in 11 Paesi si rileva gi\u00e0 una crescita dell&#8217;incidenza e in 21 si prevede un aumento imminente. Fortunatamente per\u00f2 la pressione sugli ospedali del nostro Paese &#8220;<strong>ha numeri assolutamente sotto controllo<\/strong>&#8220;, nonostante i lievi incrementi su base giornaliera, ha precisato il sottosegretario alla Salute Andrea Costa. Lo stress degli ospedali, ad oggi a livelli controllabili, \u00e8 fotografato anche dal monitoraggio dell&#8217;Agenzia nazionale per i servizi s<strong>anitari regionali (Agenas),<\/strong> aggiornati al 13 marzo 2022, secondo cui nelle ultime 24 ore l&#8217;occupazione delle terapie intensive da parte di pazienti con Covid \u00e8 stabile al 5%, sotto il livello di allerta del 10% quindi, mentre un anno fa era a quota 33%. E&#8217; ferma invece al 13% l&#8217;occupazione nei reparti ordinari, che un anno fa era 37%. Quanto all&#8217;iter di graduale allentamento delle misure restrittive, Costa ha confermato l&#8217;obiettivo del governo di eliminare il green pass da maggio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gimbe &#8220;aumenti interessano un po&#8217; tutte le Regioni e in particolare alcune del Sud e Centro come l&#8217;Umbria, la Toscana, la Calabria&#8221;<\/p>\n","protected":false},"author":55,"featured_media":165760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-165759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165759"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165760"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}