{"id":165763,"date":"2022-03-15T05:54:36","date_gmt":"2022-03-15T04:54:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/calabra-maceri-difficolta-nel-trattamento-del-residuo-linvito-ai-cittadini-a-collaborare\/"},"modified":"2023-01-16T17:01:44","modified_gmt":"2023-01-16T16:01:44","slug":"447758-calabra-maceri-difficolta-nel-trattamento-del-residuo-linvito-ai-cittadini-a-collaborare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/447758-calabra-maceri-difficolta-nel-trattamento-del-residuo-linvito-ai-cittadini-a-collaborare\/","title":{"rendered":"Calabra Maceri, difficolt\u00e0 nel trattamento del residuo. L&#8217;invito ai cittadini a collaborare"},"content":{"rendered":"<p>COSENZA &#8211; Il blocco dei trasferimenti dei container allo scalo di Gioia Tauro a causa del conflitto in Ucraina, gli stoccaggi al limite del consentito e l\u2019impossibilit\u00e0 per la Societ\u00e0 Calabra Maceri di smaltire gli scarti di lavorazione delle linee di trattamento dei rifiuti urbani hanno <strong>costretto la stessa societ\u00e0<\/strong>\u00a0a <strong>ridurre<\/strong> drasticamente gli ingressi <strong>nell\u2019impianto di trattamento di Rende,<\/strong> con la conseguenza che \u00e8 notevolmente limitata la capacit\u00e0 di accogliere nello stesso impianto i rifiuti indifferenziati.<\/p>\n<p>Le difficolt\u00e0 sono state comunicate da \u201c<strong>Calabra Maceri e servizi Spa<\/strong>\u201d a tutti i comuni <strong>dell\u2019Ambito territoriale ottimale (ATO<\/strong>) di Cosenza. A seguito della comunicazione, il sindaco Franz Caruso e l&#8217;Amministrazione comunale invitano la cittadinanza a limitare l&#8217;esposizione della frazione residuale ai soli casi in cui sia <strong>strettamente necessario, al fine di tutelare il decoro e l&#8217;igiene pubblica<\/strong>.<\/p>\n<p>L&#8217;Amministrazione comunale ricorda, altres\u00ec, che una corretta pratica di differenziazione dei rifiuti, consente, con un minimo sforzo da parte di tutti, di diminuire i quantitativi da smaltire in discarica, salvaguardando l&#8217;ambiente e riducendo le spese a carico della collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calabra Maceri ha comunicato la limitata capacit\u00e0 di accogliere i rifiuti indifferenziati e l&#8217;Amministrazione comunale di Cosenza invita i cittadini ad esporre il residuo solo se strettamente necessario<\/p>\n","protected":false},"author":42,"featured_media":165764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-165763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165763"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165764"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}