{"id":165835,"date":"2022-03-16T08:03:45","date_gmt":"2022-03-16T07:03:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/vinta-una-casa-a-rende-e-la-173esima-dal-lancio-di-vincicasa\/"},"modified":"2023-01-16T17:01:47","modified_gmt":"2023-01-16T16:01:47","slug":"447971-vinta-una-casa-a-rende-e-la-173esima-dal-lancio-di-vincicasa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/447971-vinta-una-casa-a-rende-e-la-173esima-dal-lancio-di-vincicasa\/","title":{"rendered":"Vinta una casa a Rende, \u00e8 la 173esima dal lancio di VinciCasa"},"content":{"rendered":"<p>RENDE &#8211; Nell\u2019estrazione di ieri, marted\u00ec 15 marzo 2022 \u00e8 stata vinta <strong>una casa e 200mila<\/strong> <strong>euro<\/strong> subito grazie al VinciCasa, la formula di gioco della famiglia Win for Life di Sisal, che mette in palio un premio incentrato su un bene concreto e tangibile: la casa.<\/p>\n<p>Il \u201c5\u201d infatti, \u00e8 stato centrato a Rende presso il punto vendita <strong>Sisal di Broccolo Claudio<\/strong> situato in <strong>Via Marconi <\/strong>con una <strong>schedina Tastiera<\/strong>. La combinazione vincente \u00e8 stata: <strong>4-10-17-23-32 &#8211;<\/strong> riporta l&#8217;Agenzia Agimeg. Il fortunato giocatore potr\u00e0 scegliere la casa che desidera, in massima libert\u00e0, su tutto il territorio italiano e avr\u00e0 ben 2 anni di tempo per trovarla. <strong>Dalla nascita di VinciCasa, sono ben 173 le case assegnate<\/strong>.<\/p>\n<h4>&#8220;A vincere la casa probabilmente una donna oppure realizzata con una giocata in abbonamento&#8221;<\/h4>\n<p>&#8220;Abbiamo un&#8217;ipotesi su chi possa essere il fortunato vincitore. Potrebbe trattarsi di una signora, dal momento che ieri nel mio locale \u00e8 stata realizzata una sola giocata. Ma non \u00e8 una certezza, potrebbe anche trattarsi di una giocata in abbonamento. Non sono riuscito a vedere la signora neanche dalle telecamere, la giocata \u00e8 stata fatta in un momento di confusione&#8221;. E&#8217; quanto ha dichiarato ad Agimeg ClaudioBroccolo, titolare del punto vendita.<\/p>\n<p>&#8220;E&#8217; stato il mio collega a giocarla, \u00e8 un po&#8217; attempato, quindi non si ricorda bene se sia stata una signora o un abbonamento fatto nei giorni scorsi- aggiunge scherzando. &#8211; La nostra \u00e8 una clientela universitaria. Ci troviamo presso l&#8217;uscita di un&#8217;autostrada, per questo pu\u00f2 esser stato chiunque, anche un turista. Io questa mattina pensavo fosse stato un corriere a vincere. La nostra \u00e8 una ricevitoria fortunata. Circa un mese fa \u00e8 stato realizzato un terno da 68mila. Ma anche un &#8216;5&#8217; al Superenalotto e un Gratta e Vinci che ha regalato 100mila euro. Spero &#8211; ha concluso &#8211; che la vincita sia stata di aiuto per la vita, per chiunque sia stato a realizzarla&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla nascita di VinciCasa, sono ben 173 le case assegnate. Il \u201c5\u201d \u00e8 stato centrato a Rende nell\u2019estrazione di ieri, marted\u00ec 15 marzo 2022<\/p>\n","protected":false},"author":42,"featured_media":165836,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-165835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=165835"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/165835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/165836"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=165835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=165835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=165835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}