{"id":166028,"date":"2022-03-19T07:21:41","date_gmt":"2022-03-19T06:21:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/riciclaggio-e-usura-sequestrati-beni-per-900mila-euro\/"},"modified":"2023-01-16T17:02:00","modified_gmt":"2023-01-16T16:02:00","slug":"448405-riciclaggio-e-usura-sequestrati-beni-per-900mila-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/448405-riciclaggio-e-usura-sequestrati-beni-per-900mila-euro\/","title":{"rendered":"Riciclaggio e usura, sequestrati beni per 900mila euro"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Beni per un valore di 900 mila euro sono stati sequestrati dalla Guardia di Finanza di Trieste e Vibo, a tre soggetti indagati per <strong>riciclaggio, usura e ricettazione, aggravati dalla matrice mafiosa<\/strong>. Il sequestro preventivo \u00e8 stato disposto a seguito degli esiti dell&#8217;operazione &#8216;<strong>Adelphi<\/strong>&#8216; che aveva rivelato l&#8217;esistenza di una <strong>strutturata organizzazione criminale dedita al narcotraffico internazionale<\/strong> operante nell&#8217;intero territorio nazionale, tra Calabria, Puglia, Lazio, Lombardia, Emilia-Romagna e Veneto. Gli elementi apicali del sodalizio sono risultati <strong>co-finanziatori e\/o destinatari<\/strong> di ingenti quantitativi di <strong>cocaina<\/strong>, importati in territorio nazionale dal Sudamerica (Argentina, Brasile, Bolivia, Colombia, Ecuador).<\/p>\n<p>In particolare, nell&#8217;ambito del procedimento penale era stata stralciata la posizione di alcuni soggetti vicini all&#8217;organizzazione i quali si sarebbero occupati di investire il denaro derivante dalla vendita della sostanza stupefacente tramite l&#8217;acquisizione del controllo di attivit\u00e0 economiche e attraverso la pratica dell&#8217;usura. Le indagini hanno dimostrato che <strong>uno degli indagati, promotore finanziario operante a Milano<\/strong>, <strong>gestiva i proventi dei traffici illeciti, riciclandoli attraverso capillari versamenti sulle posizioni di conto corrente bancarie e postali intestate a imprenditori usurati,<\/strong> applicando nei confronti degli stessi un tasso d&#8217;interesse fino al 174%. Il denaro prestato alle vittime tornava, quindi, nella disponibilit\u00e0 dell&#8217;organizzazione, dopo l&#8217;esecuzione di molteplici sostituzioni e trasferimenti. Le acquisizioni investigative hanno permesso, inoltre, di rivelare le condotte poste in essere con il promotore finanziario da altri due indagati incaricati del trasporto del denaro contante e dell&#8217;occultamento di parte dei proventi illeciti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I beni sequestrati a tre soggetti a seguito di quanto emerso dagli esiti dell&#8217;operazione &#8216;Adelphi&#8217; contro un&#8217;organizzazione criminale dedita al narcotraffico internazionale<\/p>\n","protected":false},"author":42,"featured_media":166029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-166028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166028"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166029"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}