{"id":166174,"date":"2022-03-22T08:33:04","date_gmt":"2022-03-22T07:33:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-rossano-denuncio-violenze-e-sevizie-donna-ritratta-le-accuse\/"},"modified":"2023-01-16T17:02:10","modified_gmt":"2023-01-16T16:02:10","slug":"448813-corigliano-rossano-denuncio-violenze-e-sevizie-donna-ritratta-le-accuse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/448813-corigliano-rossano-denuncio-violenze-e-sevizie-donna-ritratta-le-accuse\/","title":{"rendered":"Corigliano Rossano, denunci\u00f2 violenze e sevizie: donna ritratta le accuse"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211;<strong> Aveva denunciato &#8220;il branco&#8221; per estorsione, violenza sessuale e sevizie di gruppo.<\/strong> Una donna di origini albanesi aveva denunciato anche le minacce di diffondere video hard, e di essere in rapporti con uno degli imputati che poi l\u2019avrebbero costretta a prostituirsi. Ora, dopo tre anni, ritratta tutto.<\/p>\n<p>Le accuse, all&#8217;epoca dei fatti ricaddero su cinque cittadini coriglianorossanesi: <strong>Pierluigi Gallo, Sergio Gallo, William Oranges, Gianni Montalto e Salvatore Bruno.<\/strong> Quest&#8217;ultimi finirono dietro le sbarre alla vigilia di Ferragosto del 2019 per poi essere rimessi in libert\u00e0 dopo due settimane. Un fatto che fece rabbrividire i concittadini di Corigliano e non solo. E&#8217; notizia di qualche ora che Gip presso il Tribunale di Castrovillari <strong>ha archiviato il procedimento a carico dei cinque, scagionandoli completamente<\/strong> dalle gravi accuse di estorsione, violenza sessuale e sevizie di gruppo.<\/p>\n<p>Gi\u00e0 in sede di discussione delle istanze di riesame, il Tdl di Catanzaro aveva annullato le ordinanze di custodia cautelare (decisione poi confermata anche dalla Corte di Cassazione). Il provvedimento del Gip, emesso lo scorso 15 marzo,<strong> dispone l\u2019archiviazione e la restituzione degli atti al Pubblico Ministero,<\/strong> essendosi nel frattempo registrata &#8220;l\u2019evidente contraddizione nella quale \u00e8 intercorsa la persona offesa, la quale ha radicalmente cambiato versione dei fatti, <strong>affermando da ultimo di aver inventato ogni accusa nei confronti degli imputati, in quanto spinta dal marito e da un avvocat<\/strong>o&#8221;. A supporto anche le dichiarazioni rese dal medico della donna, che riferiva di una patologia quale causa delle lesioni, nonch\u00e9 gli esiti dei tabulati telefonici, che sconfessavano le sue accuse originarie. <strong>Nessuna violenza sessuale di gruppo, nessuna estorsione sotto la minaccia di diffondere dei filmati. Nulla di nulla.<\/strong> Tant\u2019\u00e8 che la donna, la quale nell\u2019agosto 2021 ha ritrattato tutto, \u00e8 stata ritenuta dai giudici &#8220;n\u00e9 credibile, n\u00e9 attendibile. Prosciolti da ogni accusa, le cinque persone \u2013 difesi dagli avvocati Giacinto D\u2019Urso, Vincenzo Reda, Francesco Cornicello, Giovanni Antonio Scatozza, Pasquale Madeo, Ivan Iurlo \u2013 e il caso \u00e8 archiviato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna ha radicalmente cambiato versione dei fatti, affermando di aver inventato ogni accusa spinta dal marito e da un avvocato<\/p>\n","protected":false},"author":60,"featured_media":166175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-166174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166174"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166175"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}